{"id":94964,"date":"2025-05-05T08:13:47","date_gmt":"2025-05-05T08:13:47","guid":{"rendered":"https:\/\/heartoforleans.ca\/?page_id=94964"},"modified":"2026-07-08T12:17:38","modified_gmt":"2026-07-08T12:17:38","slug":"temoignages","status":"publish","type":"page","link":"https:\/\/heartoforleans.ca\/fr\/a-notre-sujet\/temoignages\/","title":{"rendered":"T\u00e9moignages"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"94964\" class=\"elementor elementor-94964 elementor-94915\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11bdbdd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11bdbdd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44e9231\" data-id=\"44e9231\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b1aefb elementor-align-left elementor-widget elementor-widget-breadcrumbs\" data-id=\"8b1aefb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/heartoforleans.ca\/fr\/\">Home<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4a59698 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4a59698\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e986c49\" data-id=\"e986c49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5de3a4d elementor-widget elementor-widget-heading\" data-id=\"5de3a4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Temoignages<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac46aba elementor-widget elementor-widget-text-editor\" data-id=\"ac46aba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il est toujours agr\u00e9able de recevoir des commentaires positifs de nos membres et membres associ\u00e9s. Cela nous aide \u00e0 comprendre ce que nous faisons bien et sur quoi nous devrions nous concentrer.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11485f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11485f3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2723391\" data-id=\"2723391\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fc56c0c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc56c0c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3b7c629\" data-id=\"3b7c629\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-157dab6 elementor-widget elementor-widget-video\" data-id=\"157dab6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/svezWBCTFEg&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8b7ccac\" data-id=\"8b7ccac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e913316 elementor-widget elementor-widget-heading\" data-id=\"e913316\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">March\u00e9 du C\u0153ur d'Orl\u00e9ans<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faafcd3 elementor-widget elementor-widget-text-editor\" data-id=\"faafcd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"isSelectedEnd\">Je connais la ZAC depuis tr\u00e8s longtemps. J&#8217;avais un spa sur le boulevard Saint-Joseph il y a plus de dix ans maintenant. Nous sommes rest\u00e9s en contact et, \u00e0 la fin de 2024, la ZAC m&#8217;a approch\u00e9e pour savoir si j&#8217;aimerais organiser un march\u00e9 ici. J&#8217;ai de l&#8217;exp\u00e9rience dans l&#8217;organisation de march\u00e9s puisque je g\u00e8re \u00e9galement le March\u00e9 de Navan. Je me suis donc dit : \u00ab Pourquoi ne pas en ajouter un deuxi\u00e8me? \u00bb<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-895cae8 elementor-widget elementor-widget-text-editor\" data-id=\"895cae8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>La ZAC est formidable. L&#8217;\u00e9quipe est tr\u00e8s pr\u00e9sente, communique tr\u00e8s bien avec moi, et nous travaillons main dans la main pour faire de ce march\u00e9 une r\u00e9ussite. Elle nous fournit des sacs \u00e0 distribuer, fait la promotion du march\u00e9, et nous appuie de nombreuses fa\u00e7ons. C&#8217;est un v\u00e9ritable plaisir de collaborer avec elle pour offrir ce march\u00e9 \u00e0 la communaut\u00e9 d&#8217;Orl\u00e9ans.\u00a0<\/p><p>\u00a0<\/p><p>Amanda Watson<\/p><p>\u00a0<\/p><p>Propri\u00e9taire du march\u00e9<\/p><p>\u00a0<\/p><p>290, boulevard Centrum, Orl\u00e9ans<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-838a03f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"838a03f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa0f06d\" data-id=\"aa0f06d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-19ab49e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19ab49e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ed3c9ef\" data-id=\"ed3c9ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bdd2ea6 elementor-widget elementor-widget-video\" data-id=\"bdd2ea6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/EcAqqresSYo&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bb2cd02\" data-id=\"bb2cd02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0e0a18 elementor-widget elementor-widget-heading\" data-id=\"c0e0a18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Fire-Alert<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8738aef elementor-widget elementor-widget-text-editor\" data-id=\"8738aef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fire-Alert est fier d\u2019\u00eatre membre de la ZAC du C\u0153ur d&#8217;Orl\u00e9ans. Nous avons eu la chance de pouvoir rendre visite aux commerces locaux de cette association lors de nos \u00e9v\u00e9nements r\u00e9guliers. Ce que je trouve particuli\u00e8rement enrichissant, ce sont les liens que nous tissons et les opportunit\u00e9s qui s\u2019ouvrent \u00e0 nous lorsque nous travaillons ensemble ; cela nous permet d\u2019\u00eatre bien plus forts en tant que chefs d\u2019entreprise, car nous contribuons tous ensemble au d\u00e9veloppement \u00e9conomique de nos communaut\u00e9s.\u00a0<\/p><p>\u00a0<\/p><p>Charles Boyer<\/p><p>\u00a0<\/p><p>Directeur des relations avec la client\u00e8le et des franchises<\/p><p>\u00a0<\/p><p>890 Taylor Creek Dr, Orl\u00e9ans<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-be167c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"be167c4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c2956eb\" data-id=\"c2956eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-579a4d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"579a4d2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-438b792\" data-id=\"438b792\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28a5a07 elementor-widget elementor-widget-video\" data-id=\"28a5a07\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/q4VJ2x-vJKo&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-24ad1f7\" data-id=\"24ad1f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5eb8ebc elementor-widget elementor-widget-heading\" data-id=\"5eb8ebc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Aqua-Tots Swim School<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b94786 elementor-widget elementor-widget-text-editor\" data-id=\"4b94786\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"42\" data-end=\"464\">Faire partie de la ZAC m\u2019a permis de rencontrer mes voisins, de partager avec d\u2019autres entreprises et de cr\u00e9er des relations d\u2019affaires entre entreprises. Ils \u00e9taient \u00e9galement l\u00e0 pour m\u2019aider lors de mon ouverture. Ils sont venus avec une banni\u00e8re, ont fait en sorte que tout le monde soit au courant de mon ouverture, m\u2019ont donn\u00e9 quelques conseils et astuces, et cela a vraiment contribu\u00e9 au succ\u00e8s de l\u2019ouverture.\u00a0<\/p><p data-start=\"42\" data-end=\"464\">\u00a0<\/p><p data-start=\"466\" data-end=\"531\">Rebecca Swedlove<\/p><p data-start=\"466\" data-end=\"531\"><br data-start=\"482\" data-end=\"485\" \/>Propri\u00e9taire<\/p><p data-start=\"466\" data-end=\"531\"><br data-start=\"497\" data-end=\"500\" \/>110, Place d\u2019Orl\u00e9ans, Orl\u00e9ans<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-588254d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"588254d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-978800b\" data-id=\"978800b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c9b0695 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c9b0695\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f8a1e19\" data-id=\"f8a1e19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e834f8 elementor-widget elementor-widget-video\" data-id=\"6e834f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=3jUDm1uVnio&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2492fe6\" data-id=\"2492fe6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d4368d elementor-widget elementor-widget-heading\" data-id=\"3d4368d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Bloom Hockey Training Academy<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdb03c2 elementor-widget elementor-widget-text-editor\" data-id=\"fdb03c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La ZAC a \u00e9t\u00e9 formidable. Cela a \u00e9t\u00e9 une occasion incroyable pour nous de nouer des contacts. Ils ont organis\u00e9 plusieurs petits-d\u00e9jeuners et d\u00e9jeuners qui nous ont permis de rencontrer d&#8217;autres membres de la communaut\u00e9. Cela nous a permis de nous d\u00e9velopper. Ils ont fait un travail fantastique et cela a \u00e9t\u00e9 formidable de travailler avec eux.\u00a0<\/p><p>\u00a0<\/p><p>Rick Dorval<\/p><p>\u00a0<\/p><p>Propri\u00e9taire<\/p><p>\u00a0<\/p><p>1344, promenade Youville, A3, Orl\u00e9ans<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b383436 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b383436\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ce8432\" data-id=\"3ce8432\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f3c5fd5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f3c5fd5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e6b5dbe\" data-id=\"e6b5dbe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb7ba0b elementor-widget elementor-widget-video\" data-id=\"cb7ba0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=jcu3Kw6SqHY&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4d21ef3\" data-id=\"4d21ef3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-744e284 elementor-widget elementor-widget-heading\" data-id=\"744e284\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Mane Attraction<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aeae3b0 elementor-widget elementor-widget-text-editor\" data-id=\"aeae3b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Faire partie de la ZAC a \u00e9t\u00e9 une exp\u00e9rience merveilleuse, quelque chose de totalement nouveau pour moi. C&#8217;est une excellente fa\u00e7on d&#8217;entrer en contact avec d&#8217;autres propri\u00e9taires d&#8217;entreprises \u00e0 Orl\u00e9ans et de cr\u00e9er un r\u00e9seau.<\/p><p>\u00a0<\/p><p>Lisseth Gomez<\/p><p>Propri\u00e9taire<\/p><p>8154, boul. Jeanne-d&#8217;Arc, unit\u00e9 2, Orl\u00e9ans<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d938890 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d938890\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9c48d86\" data-id=\"9c48d86\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c846591 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c846591\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5989ea1\" data-id=\"5989ea1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f68513 elementor-widget elementor-widget-image\" data-id=\"0f68513\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/09\/fries.png\" class=\"attachment-large size-large wp-image-152668\" alt=\"\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/09\/fries.png 500w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/09\/fries-300x300.png 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/09\/fries-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0d25e4b\" data-id=\"0d25e4b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3b9bdc elementor-widget elementor-widget-heading\" data-id=\"e3b9bdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Golden Fries<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7ef249 elementor-widget elementor-widget-text-editor\" data-id=\"a7ef249\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La ZAC du C\u0153ur d\u2019Orl\u00e9ans (ZAC) a \u00e9t\u00e9 un partenaire formidable pour Golden Fries. Leur soutien, leurs initiatives cr\u00e9atives et leur communication ouverte nous font sentir connect\u00e9s \u00e0 la communaut\u00e9. Notre participation a \u00e9t\u00e9 tr\u00e8s enrichissante et il est clair qu\u2019ils travaillent constamment \u00e0 aider les entreprises locales \u00e0 r\u00e9ussir.<\/p><p>\u00a0<\/p><p>Jade Racicot<\/p><p>Propri\u00e9taire<\/p><p>Golden Fries<\/p><p>\u00a0<\/p><p>6505 Jeanne D\u2019Arc Blvd N., Orl\u00e9ans<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-05956fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"05956fd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c804107\" data-id=\"c804107\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2db3a7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2db3a7c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cb11805\" data-id=\"cb11805\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c80ee07 elementor-widget elementor-widget-image\" data-id=\"c80ee07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/09\/Place-9.jpg\" class=\"attachment-large size-large wp-image-152666\" alt=\"\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/09\/Place-9.jpg 500w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/09\/Place-9-300x300.jpg 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/09\/Place-9-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-44f9223\" data-id=\"44f9223\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f289d3 elementor-widget elementor-widget-heading\" data-id=\"4f289d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Place d'Orl\u00e9ans<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-995c0f2 elementor-widget elementor-widget-text-editor\" data-id=\"995c0f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>LA ZAC du C\u0153ur d\u2019Orl\u00e9ans (ZAC) a \u00e9t\u00e9 un partenaire tellement pr\u00e9cieux, nous aidant \u00e0 mettre en lumi\u00e8re Place d\u2019Orl\u00e9ans et les formidables entreprises locales qui s\u2019y trouvent, comme A Foot Above Fitness, New York Fries et Aqua-Tots Swim School. Nous sommes tr\u00e8s reconnaissants de leur engagement envers notre communaut\u00e9.\u00a0<\/p><p>\u00a0<\/p><p>Emma Martin<\/p><p>Directrice marketing<\/p><p>Place D&#8217;Orleans<\/p><p>\u00a0<\/p><p>110 Place d\u2019Orl\u00e9ans Dr, Orl\u00e9ans<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb439b5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb439b5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-70d3edf\" data-id=\"70d3edf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1715bb5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1715bb5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-52ae106\" data-id=\"52ae106\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ff3905 elementor-widget elementor-widget-video\" data-id=\"6ff3905\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=2IbF6ZcjMJ4&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-56bf62d\" data-id=\"56bf62d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e49e6bb elementor-widget elementor-widget-heading\" data-id=\"e49e6bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">STEMquest<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d4ab59 elementor-widget elementor-widget-text-editor\" data-id=\"7d4ab59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Neesha Gupta, Propri\u00e9taire<\/p><p>\u00a0<\/p><p>Avant que nous n&#8217;ouvrions les portes \u00e0 tout le monde, la ZAC \u00e9tait d\u00e9j\u00e0 l\u00e0. Ils nous ont soutenus depuis le premier jour, en fait, depuis le jour z\u00e9ro, avant que nous ayons commenc\u00e9 \u00e0 fonctionner.<\/p><p>\u00a0<\/p><p>260, boul. du Centrum, #202, Orl\u00e9ans<\/p><p>\u00a0<\/p><p>613-695-2719<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4d139c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4d139c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-741003a\" data-id=\"741003a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-15d0858 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15d0858\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cb9c115\" data-id=\"cb9c115\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68b3bb6 elementor-widget elementor-widget-video\" data-id=\"68b3bb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=y-4_4twKi4s&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c432c6c\" data-id=\"c432c6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c513a4 elementor-widget elementor-widget-heading\" data-id=\"8c513a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ABC Pediatric Therapies\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a2b746 elementor-widget elementor-widget-text-editor\" data-id=\"7a2b746\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sharon Burgess, ABC Pediatric Therapies<\/p><p>\u00a0<\/p><p>J&#8217;ai beaucoup appr\u00e9ci\u00e9 de travailler avec la ZAC, car elle prend l&#8217;initiative d&#8217;aller \u00e0 la rencontre des propri\u00e9taires de petites cliniques et de petites entreprises, ce que je trouve formidable, car souvent, en tant que propri\u00e9taires de petites entreprises, nous sommes surcharg\u00e9s de travail et manquons de temps. Ils sont tr\u00e8s dou\u00e9s pour tendre la main et offrir leur soutien.<\/p><p>\u00a0<\/p><p>3095, boul. St-Joseph, bureau 201-202, Orl\u00e9ans<\/p><p>\u00a0<\/p><p>613-834-2229<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9e9d7fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9e9d7fa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41a0012\" data-id=\"41a0012\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-da14e40 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da14e40\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-db84768\" data-id=\"db84768\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6410eac elementor-widget elementor-widget-video\" data-id=\"6410eac\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=5-AQxvDzqas&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a4851e3\" data-id=\"a4851e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d4535f elementor-widget elementor-widget-heading\" data-id=\"3d4535f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Bellefleur Fitness\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ea9f5e elementor-widget elementor-widget-text-editor\" data-id=\"6ea9f5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Megan Bellefleur, Bellefleur Fitness<\/p><p>\u00a0<\/p><p>J&#8217;ai en fait fait partie du conseil d&#8217;administration de la ZAC pendant quelques ann\u00e9es. La ZAC a \u00e9t\u00e9 un grand d\u00e9fenseur des petites entreprises.<\/p><p>\u00a0<\/p><p>3095, boulevard Saint-Joseph, Orl\u00e9ans<\/p><p>613-424-7852<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19b4bed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19b4bed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e28c91\" data-id=\"1e28c91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4db12a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4db12a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-249c26e\" data-id=\"249c26e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d824776 elementor-widget elementor-widget-video\" data-id=\"d824776\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=OmnOreibMU4&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-279c3bb\" data-id=\"279c3bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b522fc elementor-widget elementor-widget-heading\" data-id=\"1b522fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Orl\u00e9ans Craft Beer Festival\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ad8c0e elementor-widget elementor-widget-text-editor\" data-id=\"4ad8c0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kevin Hurtubise, Orl\u00e9ans Festivals<\/p><p>\u00a0<\/p><div class=\"text-base my-auto mx-auto py-5 [--thread-content-margin:--spacing(4)] @[37rem]:[--thread-content-margin:--spacing(6)] @[72rem]:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\"><div class=\"[--thread-content-max-width:32rem] @[34rem]:[--thread-content-max-width:40rem] @[64rem]:[--thread-content-max-width:48rem] mx-auto flex max-w-(--thread-content-max-width) flex-1 text-base gap-4 md:gap-5 lg:gap-6 group\/turn-messages focus-visible:outline-hidden\" tabindex=\"-1\"><div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn\"><div class=\"relative flex-col gap-1 md:gap-3\"><div class=\"flex max-w-full flex-col grow\"><div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"9962c993-b8f3-4acf-a694-4b94f0e10260\" data-message-model-slug=\"gpt-4o\"><div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\"><div class=\"markdown prose dark:prose-invert w-full break-words light\"><p data-start=\"0\" data-end=\"377\" data-is-last-node=\"\" data-is-only-node=\"\">Ces \u00e9v\u00e9nements ne pourraient pas avoir lieu sans le soutien local, et la ZAC a \u00e9t\u00e9 un commanditaire formidable pour nous. Elle s\u2019associe \u00e0 nous chaque ann\u00e9e et offre une belle visibilit\u00e9 \u00e0 la communaut\u00e9. Nous travaillons avec plusieurs de leurs commer\u00e7ants locaux ici, au c\u0153ur de la ZAC du C\u0153ur d\u2019Orl\u00e9ans. Nous n\u2019avons que de bons mots \u00e0 leur sujet. Ils sont fantastiques !\u00a0<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b9522c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9b9522c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-06e9d50\" data-id=\"06e9d50\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-67b699f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67b699f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-090c7cd\" data-id=\"090c7cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3b1a37 elementor-widget elementor-widget-video\" data-id=\"d3b1a37\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=0V2NZnsc9rs&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-568fc71\" data-id=\"568fc71\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4ff60e elementor-widget elementor-widget-heading\" data-id=\"f4ff60e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3 Brothers Shawarma &amp; Poutine\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee91169 elementor-widget elementor-widget-text-editor\" data-id=\"ee91169\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Eddy Zein, propri\u00e9taire<\/p><p>\u00a0<\/p><p>La ZAC a \u00e9t\u00e9 tr\u00e8s utile et tr\u00e8s bon pour nous. Ils passent nous voir et nous demandent si nous avons besoin d&#8217;aide, de soutien ou de quoi que ce soit d&#8217;autre.\u00a0<\/p><p>\u00a0<\/p><p>6505 Jeanne D\u2019Arc Blvd N., Orl\u00e9ans<\/p><p>613-837-1500<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7106484 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7106484\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2386732 team_user_details\" data-id=\"2386732\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2f5544f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f5544f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-697038c\" data-id=\"697038c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a369f0 elementor-widget elementor-widget-image\" data-id=\"6a369f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"608\" src=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/Orleans-Cumberland-Community-Resource-Centre-1-1024x608.jpg\" class=\"attachment-large size-large wp-image-94665\" alt=\"\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/Orleans-Cumberland-Community-Resource-Centre-1-1024x608.jpg 1024w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/Orleans-Cumberland-Community-Resource-Centre-1-300x178.jpg 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/Orleans-Cumberland-Community-Resource-Centre-1-768x456.jpg 768w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/Orleans-Cumberland-Community-Resource-Centre-1-1536x912.jpg 1536w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/Orleans-Cumberland-Community-Resource-Centre-1-2048x1216.jpg 2048w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/Orleans-Cumberland-Community-Resource-Centre-1-1200x713.jpg 1200w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/Orleans-Cumberland-Community-Resource-Centre-1-1400x831.jpg 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e9d9620\" data-id=\"e9d9620\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d2b920 elementor-widget elementor-widget-heading\" data-id=\"6d2b920\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">YMCA de la r\u00e9gion de la capitale nationale\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85a6700 elementor-widget elementor-widget-text-editor\" data-id=\"85a6700\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>**D\u00e8s le premier jour de l\u2019ouverture de notre site \u00e0 Orl\u00e9ans, nous avons \u00e9t\u00e9 chaleureusement accueillis par Rita Chalabi de la ZAC C\u0153ur d\u2019Orl\u00e9ans. Rita a pris le temps de nous rendre visite en personne, nous souhaitant la bienvenue avec sinc\u00e9rit\u00e9 et nous offrant son soutien pour faciliter notre int\u00e9gration dans la communaut\u00e9 d\u2019affaires locale.<\/p><p>\u00a0<\/p><p>Son approche proactive et sa collaboration continue ont \u00e9t\u00e9 inestimables \u2014 en particulier pour nous aider \u00e0 cr\u00e9er des liens avec les organisations locales et les r\u00e9sidents. Un moment fort a \u00e9t\u00e9 notre partenariat lors du Salon de l\u2019emploi du printemps du YMCA, o\u00f9 la ZAC a jou\u00e9 un r\u00f4le cl\u00e9 dans le soutien et la promotion de l\u2019\u00e9v\u00e9nement au sein de la communaut\u00e9.**<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-efc5eb4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"efc5eb4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a78608b\" data-id=\"a78608b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ad8368 elementor-widget elementor-widget-text-editor\" data-id=\"0ad8368\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous sommes reconnaissants du soutien continu de la ZAC C\u0153ur d\u2019Orl\u00e9ans et avons h\u00e2te de renforcer encore davantage nos liens \u00e0 l\u2019avenir.<\/p><p>Soukaina Baghdad<br \/>Directrice, Centre d\u2019acc\u00e8s en emploi<br \/>YMCA de la r\u00e9gion de la capitale nationale<br \/>240, boulevard Centrum, Suite 105, Ottawa (ON) K1E 3V8<br \/>T : 343-588-1680<br \/><a href=\"mailto:soukaina.baghdad@ymcaottawa.ca\">soukaina.baghdad@ymcaottawa.ca<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e91fbde quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e91fbde\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ddc0329 team_user_details\" data-id=\"ddc0329\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b3958f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b3958f0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b251fdb\" data-id=\"b251fdb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41d1d1d elementor-widget elementor-widget-video\" data-id=\"41d1d1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=evTpgPjDSyE&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7a5d7d5\" data-id=\"7a5d7d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6d9f3d elementor-widget elementor-widget-heading\" data-id=\"f6d9f3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Prosoya<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23d1e15 elementor-widget elementor-widget-text-editor\" data-id=\"23d1e15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>**Travailler avec la Zone d\u2019Am\u00e9lioration Commerciale (ZAC) d\u2019Orl\u00e9ans a \u00e9t\u00e9 une exp\u00e9rience extr\u00eamement positive pour ProSoya. D\u00e8s le d\u00e9part, nous nous sommes sentis accueillis, soutenus et vraiment int\u00e9gr\u00e9s \u00e0 une communaut\u00e9 d\u2019affaires dynamique. L\u2019\u00e9nergie et la passion que la ZAC apporte aux entreprises locales sont incomparables \u2014 et c\u2019est en grande partie gr\u00e2ce \u00e0 Rita.<\/p><p>\u00a0<\/p><p>Rita est tout simplement formidable. Elle se d\u00e9passe constamment pour connecter, soutenir et promouvoir les entreprises de la r\u00e9gion. Son engagement, sa r\u00e9activit\u00e9 et ses id\u00e9es novatrices ont eu un impact direct sur notre visibilit\u00e9 et notre croissance. Qu\u2019il s\u2019agisse d\u2019organiser des \u00e9v\u00e9nements communautaires, de mettre en lumi\u00e8re les entreprises locales ou de nous aider \u00e0 \u00e9laborer des strat\u00e9gies de marketing, Rita et l\u2019\u00e9quipe de la ZAC sont toujours l\u00e0 quand nous avons besoin d\u2019eux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c15d922 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c15d922\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0e09f3d\" data-id=\"0e09f3d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26ba75d elementor-widget elementor-widget-text-editor\" data-id=\"26ba75d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La ZAC d\u2019Orl\u00e9ans offre une vaste gamme de services v\u00e9ritablement utiles \u2014 des campagnes marketing aux \u00e9v\u00e9nements de r\u00e9seautage communautaire, en passant par les projets d\u2019embellissement et le plaidoyer. Faire partie de cette organisation a \u00e9t\u00e9 un v\u00e9ritable tournant pour nous. Nous sommes fiers d\u2019en \u00eatre membres et reconnaissants pour tout ce qu\u2019ils font pour aider les entreprises comme la n\u00f4tre \u00e0 prosp\u00e9rer.**<\/p><p>\u2014 L\u2019\u00e9quipe de ProSoya<br \/><strong>Zachariah Hart<\/strong><br \/>Sp\u00e9cialiste des ventes | <strong>PROSOYA INC.<\/strong><br \/>Courriel : <a href=\"mailto:zach@prosoya.com\">zach@prosoya.com<\/a> | www.prosoya.com<br \/>550, chemin Lacolle, Ottawa, ON K4A 0N9 | Cell. : 613-716-9723 | T\u00e9l\u00e9c. : 613-745-2045<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e3c6c9c quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e3c6c9c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d7e2a62 team_user_details\" data-id=\"d7e2a62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a769212 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a769212\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ecadd13\" data-id=\"ecadd13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-125ee4b elementor-widget elementor-widget-image\" data-id=\"125ee4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"732\" src=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/20250307-1DX21496-Edit-2048-1024x732.jpg\" class=\"attachment-large size-large wp-image-94614\" alt=\"\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/20250307-1DX21496-Edit-2048-1024x732.jpg 1024w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/20250307-1DX21496-Edit-2048-300x214.jpg 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/20250307-1DX21496-Edit-2048-768x549.jpg 768w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/20250307-1DX21496-Edit-2048-1536x1097.jpg 1536w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/20250307-1DX21496-Edit-2048-1200x857.jpg 1200w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/20250307-1DX21496-Edit-2048-1400x1000.jpg 1400w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/20250307-1DX21496-Edit-2048.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9726f4d\" data-id=\"9726f4d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33a7bd6 elementor-widget elementor-widget-heading\" data-id=\"33a7bd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">La perle\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1de4817 elementor-widget elementor-widget-text-editor\" data-id=\"1de4817\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Faire partie de la ZAC C\u0153ur d\u2019Orl\u00e9ans a \u00e9t\u00e9 une exp\u00e9rience incroyablement enrichissante pour nous \u00e0 La Perle. L\u2019engagement de la ZAC \u00e0 favoriser les liens entre les membres gr\u00e2ce \u00e0 des \u00e9v\u00e9nements de r\u00e9seautage r\u00e9guliers nous a permis de tisser des relations solides au sein de la communaut\u00e9 d\u2019affaires locale. Ces rencontres sont toujours bien organis\u00e9es, accueillantes et remplies d\u2019une belle \u00e9nergie \u2014 un vrai reflet de l\u2019esprit d\u2019Orl\u00e9ans.<\/p><p>Nous sommes fiers d\u2019y participer activement et reconnaissants pour les occasions de collaborer, d\u2019\u00e9changer des id\u00e9es et de grandir ensemble. Merci de soutenir les entreprises locales et de faire d\u2019Orl\u00e9ans un endroit aussi dynamique pour prosp\u00e9rer !<br \/>\u2014 Makayla Wellman, La Perle<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-08c812a quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"08c812a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b93242 team_user_details\" data-id=\"7b93242\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4134126 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4134126\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-215c9a3\" data-id=\"215c9a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27c7dc8 elementor-widget elementor-widget-image\" data-id=\"27c7dc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"721\" src=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/The-Avid-Host_2_-September-2024-1-1-1024x721.jpg\" class=\"attachment-large size-large wp-image-94611\" alt=\"\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/The-Avid-Host_2_-September-2024-1-1-1024x721.jpg 1024w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/The-Avid-Host_2_-September-2024-1-1-300x211.jpg 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/The-Avid-Host_2_-September-2024-1-1-768x541.jpg 768w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/The-Avid-Host_2_-September-2024-1-1-1536x1082.jpg 1536w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/The-Avid-Host_2_-September-2024-1-1-2048x1443.jpg 2048w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/The-Avid-Host_2_-September-2024-1-1-1200x845.jpg 1200w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/04\/The-Avid-Host_2_-September-2024-1-1-1400x986.jpg 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4377d48\" data-id=\"4377d48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4966a65 elementor-widget elementor-widget-heading\" data-id=\"4966a65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">The Avid Host\n\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-684e9cc elementor-widget elementor-widget-text-editor\" data-id=\"684e9cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t**Nous sommes extr\u00eamement reconnaissants pour le soutien et le partenariat que nous avons re\u00e7us de la part de la ZAC C\u0153ur d\u2019Orl\u00e9ans ! Leur engagement \u00e0 soutenir les entreprises locales est non seulement admirable, mais r\u00e9ellement porteur d\u2019impact. D\u00e8s le premier jour, ils ont fait bien plus que le n\u00e9cessaire pour promouvoir notre entreprise, en nous connectant \u00e0 la communaut\u00e9 et en augmentant notre visibilit\u00e9 de mani\u00e8re significative.\n\nIl est clair qu\u2019ils se soucient sinc\u00e8rement du succ\u00e8s des entreprises locales \u00e0 Orl\u00e9ans. Leur \u00e9quipe est professionnelle, engag\u00e9e et toujours proactive dans la recherche de nouvelles fa\u00e7ons de collaborer et de cr\u00e9er de la valeur. Nous sommes fiers de faire partie de ce r\u00e9seau dynamique et avons h\u00e2te de continuer \u00e0 cro\u00eetre ensemble.\n\nMerci de toujours d\u00e9fendre les entreprises locales \u2014 vous avez r\u00e9ellement fait une diff\u00e9rence pour nous !**\n\nKathy et Glen\nThe Avid Host\n<a href=\"https:\/\/theavidhost.com\/\" target=\"_blank\">TheAvidHost.com<\/a>\n\n\u00c9levez l\u2019art de recevoir \u00e0 la maison !\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13c2e24 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13c2e24\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8fea2c7 team_user_details\" data-id=\"8fea2c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5814d8b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5814d8b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-11d6776\" data-id=\"11d6776\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d4f698 elementor-widget elementor-widget-video\" data-id=\"8d4f698\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/jIiQq7_tM3w&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-39eae94\" data-id=\"39eae94\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e6bfb1 elementor-widget elementor-widget-heading\" data-id=\"3e6bfb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Zenzero Blu\n\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-521392a elementor-widget elementor-widget-text-editor\" data-id=\"521392a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Brielle Alix, Associ\u00e9 g\u00e9rant<\/p><p>\u00a0<\/p><p>J\u2019ai travaill\u00e9 un peu avec la ZAC \u00e0 No\u00ebl. Un influenceur est venu faire une petite vid\u00e9o pour nous. C\u2019\u00e9tait une exp\u00e9rience. Un repr\u00e9sentant du ZAC est \u00e9galement venu faire un peu plus de contenu pour notre Instagram. C\u2019\u00e9tait tr\u00e8s agr\u00e9able.<\/p><p>\u00a0<\/p><p>110 Place d\u2019Orl\u00e9ans Dr, Orl\u00e9ans<br \/>(437) 880-7816<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5741d4a quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5741d4a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa88d3f team_user_details\" data-id=\"aa88d3f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ac1960a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ac1960a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4344828\" data-id=\"4344828\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b7e8bc elementor-widget elementor-widget-video\" data-id=\"0b7e8bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=E0X0b7caV2U&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-af3507c\" data-id=\"af3507c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5e4c82 elementor-widget elementor-widget-heading\" data-id=\"b5e4c82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">A Foot Above Fitness\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b044d2 elementor-widget elementor-widget-text-editor\" data-id=\"8b044d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Zachary Boissinot , Propri\u00e9taire\u00a0<\/p><p>\u00a0<\/p><p>Je n&#8217;ai que de bonnes choses \u00e0 dire sur la ZAC. Je suis tr\u00e8s reconnaissant. Ce n&#8217;est qu&#8217;une bonne exp\u00e9rience jusqu&#8217;\u00e0 pr\u00e9sent.<\/p><p>\u00a0<\/p><p>110 Place d\u2019Orl\u00e9ans Dr, Orl\u00e9ans<br \/>(613) 837-2280<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cccb6e6 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cccb6e6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-066e4fd team_user_details\" data-id=\"066e4fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-483cbf0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"483cbf0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-53d1ee3\" data-id=\"53d1ee3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0116943 elementor-widget elementor-widget-image\" data-id=\"0116943\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"1024\" src=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/DSC_4163-1-1050x1536-1-700x1024.jpg\" class=\"attachment-large size-large wp-image-94936\" alt=\"\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/DSC_4163-1-1050x1536-1-700x1024.jpg 700w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/DSC_4163-1-1050x1536-1-205x300.jpg 205w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/DSC_4163-1-1050x1536-1-768x1123.jpg 768w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/DSC_4163-1-1050x1536-1-300x439.jpg 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/DSC_4163-1-1050x1536-1.jpg 1050w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-99936b9\" data-id=\"99936b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37539f5 elementor-widget elementor-widget-heading\" data-id=\"37539f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Trinity Physio<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28a4ed0 elementor-widget elementor-widget-text-editor\" data-id=\"28a4ed0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00ab La ZAC du C\u0153ur d&#8217;Orl\u00e9ans a \u00e9t\u00e9 un partenaire fantastique pour aider Trinity Physio \u00e0 cro\u00eetre et \u00e0 prosp\u00e9rer. Leur soutien et leur d\u00e9vouement aux entreprises locales font une \u00e9norme diff\u00e9rence dans la promotion d&#8217;une communaut\u00e9 forte et connect\u00e9e. Nous appr\u00e9cions vraiment leur impact !<\/p><p>\u00a0<\/p><p>&#8211; Andrew, propri\u00e9taire de Trinity Physio<\/p><p>\u00a0<\/p><p>6008, rue Voyageur Orleans On<\/p><p>613.255.5232<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73c1caf quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73c1caf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8fe0915 team_user_details\" data-id=\"8fe0915\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ae37fea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ae37fea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4b3e88d\" data-id=\"4b3e88d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-863e00c elementor-widget elementor-widget-video\" data-id=\"863e00c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=YIA-yCqCeEM&amp;t=4s&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-37a871f\" data-id=\"37a871f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba93f02 elementor-widget elementor-widget-heading\" data-id=\"ba93f02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nagi Sushi<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-244f6c6 elementor-widget elementor-widget-text-editor\" data-id=\"244f6c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Moriyuki Hiroha, Propri\u00e9taire et chef sushi<\/p><p>\u00a0<\/p><p>La communaut\u00e9 d&#8217;Orl\u00e9ans est tr\u00e8s forte. Le fait d&#8217;\u00eatre membre de la ZAC du C\u0153ur d&#8217;Orl\u00e9ans aide vraiment la communaut\u00e9 \u00e0 nous conna\u00eetre. Nous sommes tr\u00e8s reconnaissants.<\/p><p>\u00a0<\/p><p>2208 St Joseph Blvd #104, Orl\u00e9ans<br \/><span aria-label=\"Call Phone Number (613) 580-2700\">(613) 830-9770<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-570ad51 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"570ad51\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-585d7be team_user_details\" data-id=\"585d7be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-aa25394 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa25394\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-317f2d8\" data-id=\"317f2d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f1ce18 elementor-widget elementor-widget-video\" data-id=\"5f1ce18\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=u7nphKRwGp8&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-996643e\" data-id=\"996643e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e073d64 elementor-widget elementor-widget-heading\" data-id=\"e073d64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">St. Martha's Brasserie<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7417b81 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7417b81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fernando Arruda, Chef et propri\u00e9taire<\/p><p>\u00a0<\/p><p>La ZAC fait partie int\u00e9grante de notre entreprise. Nous les voyons souvent venir ici et ils nous demandent toujours comment vont les choses et comment ils peuvent nous aider. Nous avons eu une tr\u00e8s bonne relation de travail, tr\u00e8s ouverte.<\/p><p>\u00a0<\/p><div><div>3095 St Joseph Blvd #305, Orl\u00e9ans<\/div><div><div class=\"x9f619 x1n2onr6 x1ja2u2z x78zum5 x2lah0s x1nhvcw1 x1qjc9v5 xozqiw3 x1q0g3np xyamay9 xykv574 xbmpl8g x4cne27 xifccgj\"><div class=\"x9f619 x1n2onr6 x1ja2u2z x78zum5 x2lah0s x1nhvcw1 x1qjc9v5 xozqiw3 x1q0g3np xyamay9 xykv574 xbmpl8g x4cne27 xifccgj\"><div class=\"x9f619 x1n2onr6 x1ja2u2z x78zum5 xdt5ytf x193iq5w xeuugli x1r8uery x1iyjqo2 xs83m0k xamitd3 xsyo7zv x16hj40l x10b6aqq x1yrsyyn\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><span aria-label=\"Call Phone Number (613) 424-9199\">(613) 424-9199<\/span>\u00a0<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d0f2496 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d0f2496\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73111f6 team_user_details\" data-id=\"73111f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-562529e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"562529e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-61de528\" data-id=\"61de528\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eae7d3b elementor-widget elementor-widget-video\" data-id=\"eae7d3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=PkMRVeVmuZ0&amp;t=1s&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-93955e3\" data-id=\"93955e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-061cb6f elementor-widget elementor-widget-heading\" data-id=\"061cb6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Shenkman Arts Centre<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0318eb2 elementor-widget elementor-widget-text-editor\" data-id=\"0318eb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jahn Fawcett\/Gestionnaire de portefeuille<\/p><p>\u00a0<\/p><p>Nous sommes tr\u00e8s heureux d&#8217;avoir la BIA sur place avec nous au Centre des arts Shenkman. C&#8217;est un excellent partenaire et un connecteur dans le b\u00e2timent. Elle est \u00e9galement un commanditaire de notre programmation communautaire gratuite. Souvent, ils nous mettent en contact avec des restaurants ou de nouvelles entreprises qui veulent participer \u00e0 nos march\u00e9s ext\u00e9rieurs, \u00e0 nos march\u00e9s int\u00e9rieurs et \u00e0 nos \u00e9v\u00e9nements communautaires gratuits.<\/p><p>\u00a0<\/p><p>245 Centrum Blvd, Orl\u00e9ans<br \/><span aria-label=\"Call Phone Number (613) 580-2700\">(613) 580-2700<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48b8582 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48b8582\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-338dbe4 team_user_details\" data-id=\"338dbe4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dd9de14 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dd9de14\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7e50552\" data-id=\"7e50552\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-784ecdb elementor-widget elementor-widget-video\" data-id=\"784ecdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=kwwJi92c1iU&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5ce1f6b\" data-id=\"5ce1f6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c1b021 elementor-widget elementor-widget-heading\" data-id=\"2c1b021\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Altitude Gym<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-565ede4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"565ede4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Maxym Langlois, Gestionnaire<\/p><p>\u00a0<\/p><p>Nous sommes fiers d&#8217;\u00eatre membres de la ZAC du c\u0153ur d&#8217;Orl\u00e9ans qui fait des merveilles pour les entreprises locales de la r\u00e9gion.<\/p><p>\u00a0<\/p><div><div>265 Centrum Blvd,\u00a0Orl\u00e9ans<\/div><div><div class=\"x9f619 x1n2onr6 x1ja2u2z x78zum5 x2lah0s x1nhvcw1 x1qjc9v5 xozqiw3 x1q0g3np xyamay9 xykv574 xbmpl8g x4cne27 xifccgj\"><div class=\"x9f619 x1n2onr6 x1ja2u2z x78zum5 x2lah0s x1nhvcw1 x1qjc9v5 xozqiw3 x1q0g3np xyamay9 xykv574 xbmpl8g x4cne27 xifccgj\"><div class=\"x9f619 x1n2onr6 x1ja2u2z x78zum5 xdt5ytf x193iq5w xeuugli x1r8uery x1iyjqo2 xs83m0k xamitd3 xsyo7zv x16hj40l x10b6aqq x1yrsyyn\"><div><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\">(613) 416-5753<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-148b21c quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"148b21c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a83a5c3 team_user_details\" data-id=\"a83a5c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eea0e8a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eea0e8a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dc1fc53\" data-id=\"dc1fc53\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4516bc elementor-widget elementor-widget-video\" data-id=\"d4516bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=0mVd7QygyFU&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63c3f0d\" data-id=\"63c3f0d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3168890 elementor-widget elementor-widget-heading\" data-id=\"3168890\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Broadhead Brewery<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1de5729 elementor-widget elementor-widget-text-editor\" data-id=\"1de5729\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jamie White, Directeur g\u00e9n\u00e9ral\/Co-fondateur<\/p><p>\u00a0<\/p><p>Lorsque nous avons d\u00e9m\u00e9nag\u00e9 \u00e0 Orl\u00e9ans, nous nous sommes impliqu\u00e9s dans le BIA. Ils ont \u00e9t\u00e9 formidables. Nous avons organis\u00e9 quelques \u00e9v\u00e9nements dans notre salle de d\u00e9gustation. C&#8217;est tr\u00e8s agr\u00e9able de rencontrer d&#8217;autres propri\u00e9taires, et c&#8217;est un aspect social tr\u00e8s int\u00e9ressant qui nous permet de nous m\u00ealer aux autres et de partager des id\u00e9es. Cela nous permet de mieux nous int\u00e9grer dans la communaut\u00e9.<\/p><p>\u00a0<\/p><p>1680 Vimont Ct Unit 106, Orl\u00e9ans<br \/>(613) 380-3944<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b7f0cde quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b7f0cde\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c45ad45 team_user_details\" data-id=\"c45ad45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0b46dcf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b46dcf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cce6f00\" data-id=\"cce6f00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bedf7d elementor-widget elementor-widget-video\" data-id=\"2bedf7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=dtxFKil2L44&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4207394\" data-id=\"4207394\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2d8355 elementor-widget elementor-widget-heading\" data-id=\"c2d8355\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">BBCR Caf\u00e9<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-843c180 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"843c180\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kevin Sterling, Propri\u00e9taire<\/p><p>\u00a0<\/p><p>La ZAC du C\u0153ur d&#8217;Orl\u00e9ans a \u00e9t\u00e9 merveilleuse. Le premier jour de notre ouverture, Rita s&#8217;est pr\u00e9sent\u00e9e avec son petit sac de friandises et nous a souhait\u00e9 la bienvenue dans le quartier. Ils ont organis\u00e9 quelques petits-d\u00e9jeuners de travail ici, ainsi que d&#8217;autres r\u00e9unions de groupe. Ils organisent un tas d&#8217;autres \u00e9v\u00e9nements de mise en r\u00e9seau qui aident la communaut\u00e9 \u00e0 se rassembler et nous aident, nous les chefs d&#8217;entreprise, \u00e0 nous mettre en r\u00e9seau.<\/p><p>\u00a0<\/p><div><div>511 Lacolle Way, Orl\u00e9ans<\/div><div><div class=\"x9f619 x1n2onr6 x1ja2u2z x78zum5 x2lah0s x1nhvcw1 x1qjc9v5 xozqiw3 x1q0g3np xyamay9 xykv574 xbmpl8g x4cne27 xifccgj\"><div class=\"x9f619 x1n2onr6 x1ja2u2z x78zum5 x2lah0s x1nhvcw1 x1qjc9v5 xozqiw3 x1q0g3np xyamay9 xykv574 xbmpl8g x4cne27 xifccgj\"><div class=\"x9f619 x1n2onr6 x1ja2u2z x78zum5 xdt5ytf x193iq5w xeuugli x1r8uery x1iyjqo2 xs83m0k xamitd3 xsyo7zv x16hj40l x10b6aqq x1yrsyyn\"><div><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\">(343) 505-0110<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a22083 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7a22083\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dbf4f08 team_user_details\" data-id=\"dbf4f08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0e8df95 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e8df95\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5008b50\" data-id=\"5008b50\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-792df24 elementor-widget elementor-widget-video\" data-id=\"792df24\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=8-Lez9XYvkU&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-514798f\" data-id=\"514798f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d49b04 elementor-widget elementor-widget-heading\" data-id=\"0d49b04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Orl\u00e9ans Boat World<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b30dae elementor-widget elementor-widget-text-editor\" data-id=\"2b30dae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Marc Savage, Propri\u00e9taire<\/p><p>\u00a0<\/p><p>Nous sommes tr\u00e8s heureux de faire partie de la ZAC. Cela nous permet de d\u00e9velopper notre activit\u00e9 et d&#8217;attirer des gens de l&#8217;ext\u00e9rieur pour qu&#8217;ils viennent visiter Orl\u00e9ans, voir ce qu&#8217;elle a de beau \u00e0 offrir, et contribuer \u00e0 d\u00e9velopper non seulement la ZAC, mais aussi notre activit\u00e9. Cela favorise \u00e9galement l&#8217;emploi dans la r\u00e9gion. C&#8217;est une situation gagnant-gagnant.<\/p><p>\u00a0<\/p><p>701 Taylor Creek Dr, Orl\u00e9ans<\/p><p>(343) 338-3098<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e62ddf0 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e62ddf0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7dd489a team_user_details\" data-id=\"7dd489a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-94302c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"94302c1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-78ee6d2\" data-id=\"78ee6d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80f922d elementor-widget elementor-widget-video\" data-id=\"80f922d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=ENQkpkCrf9A&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ece68a2\" data-id=\"ece68a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-312412b elementor-widget elementor-widget-heading\" data-id=\"312412b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Aura Design<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f4ed3a elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0f4ed3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Stephane Doucet, Pr\u00e9sident<\/p><p>\u00a0<\/p><p>L&#8217;avantage de faire partie de la BIA est la mise en r\u00e9seau de toutes les entreprises, l&#8217;apprentissage par d&#8217;autres entreprises et l&#8217;aide \u00e0 se faire conna\u00eetre dans la r\u00e9gion.<\/p><p>\u00a0<\/p><div>1344 Youville Dr, Orl\u00e9ans<\/div><div><div class=\"x9f619 x1n2onr6 x1ja2u2z x78zum5 x2lah0s x1nhvcw1 x1qjc9v5 xozqiw3 x1q0g3np xyamay9 xykv574 xbmpl8g x4cne27 xifccgj\"><div class=\"x9f619 x1n2onr6 x1ja2u2z x78zum5 x2lah0s x1nhvcw1 x1qjc9v5 xozqiw3 x1q0g3np xyamay9 xykv574 xbmpl8g x4cne27 xifccgj\"><div class=\"x9f619 x1n2onr6 x1ja2u2z x78zum5 xdt5ytf x193iq5w xeuugli x1r8uery x1iyjqo2 xs83m0k xamitd3 xsyo7zv x16hj40l x10b6aqq x1yrsyyn\"><div><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\">(613) 830-6787<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e627f6 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e627f6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-99ac2c4 team_user_details\" data-id=\"99ac2c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6f59d91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f59d91\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-13239dc\" data-id=\"13239dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b82f9b8 elementor-widget elementor-widget-video\" data-id=\"b82f9b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=WaajgG_Hpr0&amp;t=1s&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ce10e8c\" data-id=\"ce10e8c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ef2149 elementor-widget elementor-widget-heading\" data-id=\"3ef2149\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Beyond Caf\u00e9<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efe4e83 elementor-widget elementor-widget-text-editor\" data-id=\"efe4e83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-size: 20px; color: #000;\">Elaheh Meschi, Copropri\u00e9taire<\/p><p>\u00a0<\/p><p>La BIA nous aide beaucoup. Elle est toujours rest\u00e9e en contact avec nous. Ils nous ont aid\u00e9s \u00e0 nous d\u00e9velopper dans cette communaut\u00e9 d\u00e8s le d\u00e9but et ils continuent \u00e0 le faire. Nous en sommes tr\u00e8s reconnaissants!<\/p><p>\u00a0<\/p><p>Elaheh Meschi, Co-Owner Beyond Caf\u00e9<\/p><p>2701 St Joseph Blvd, Orl\u00e9ans, ON K1C 1G4<span aria-label=\"Call Phone Number (613) 424-8221\">(613) 841-3166<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-85ded94 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"85ded94\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-76fe3c7 team_user_details\" data-id=\"76fe3c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-33ca158 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33ca158\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f9ec257\" data-id=\"f9ec257\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4121431 elementor-widget elementor-widget-image\" data-id=\"4121431\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"775\" src=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/MoonstoneHairStudio__5_June-2022-1400x1060-1-1024x775.jpg\" class=\"attachment-large size-large wp-image-94938\" alt=\"\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/MoonstoneHairStudio__5_June-2022-1400x1060-1-1024x775.jpg 1024w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/MoonstoneHairStudio__5_June-2022-1400x1060-1-300x227.jpg 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/MoonstoneHairStudio__5_June-2022-1400x1060-1-768x581.jpg 768w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/MoonstoneHairStudio__5_June-2022-1400x1060-1-1200x909.jpg 1200w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/MoonstoneHairStudio__5_June-2022-1400x1060-1.jpg 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c67becf\" data-id=\"c67becf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91bf8c2 elementor-widget elementor-widget-heading\" data-id=\"91bf8c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Moonstone Hair Studio<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ced499 elementor-widget elementor-widget-text-editor\" data-id=\"9ced499\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le C\u0153ur d&#8217;Orl\u00e9ans a \u00e9t\u00e9 l\u00e0 pour moi et pour mon entreprise depuis que j&#8217;ai ouvert pendant les p\u00e9riodes difficiles de la pand\u00e9mie de 2020. Ils ont fourni \u00e0 mon entreprise tous les outils pour l&#8217;aider \u00e0 se faire conna\u00eetre et \u00e0 attirer de nouveaux clients. Ils m&#8217;ont beaucoup aid\u00e9 en m&#8217;aiguillant vers des sp\u00e9cialistes locaux chaque fois que j&#8217;ai eu besoin d&#8217;externaliser des services suppl\u00e9mentaires pour l&#8217;entreprise. Le C\u0153ur d&#8217;Orl\u00e9ans est un endroit id\u00e9al pour la prosp\u00e9rit\u00e9 des petites entreprises, c&#8217;est vraiment comme une famille.<\/p><p>\u00a0<\/p><p><strong>Moonstone Hair Studio<\/strong><\/p><p>\u00a0<\/p><p>2813 St Joseph Blvd<br \/>melissa.moonstonehairstudio@gmail.com<\/p><p>moonstonehairstudio.ca<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b2a88f quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b2a88f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5606836 team_user_details\" data-id=\"5606836\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-89c231c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"89c231c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bc6670c\" data-id=\"bc6670c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0bef887 elementor-widget elementor-widget-image\" data-id=\"0bef887\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/elementor\/thumbs\/Bellefleur-Physiotherapy-scaled-r2i8svzrcjdccijkpxkp1m9bpeoa85iq480xn7xngg-r5cppzlvfw2cvzjakfstm819icycpholkn412gf3ls.jpg\" title=\"Bellefleur-Physiotherapy-scaled-r2i8svzrcjdccijkpxkp1m9bpeoa85iq480xn7xngg\" alt=\"Bellefleur-Physiotherapy-scaled-r2i8svzrcjdccijkpxkp1m9bpeoa85iq480xn7xngg\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-27b2332\" data-id=\"27b2332\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31bbf63 elementor-widget elementor-widget-heading\" data-id=\"31bbf63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Physioth\u00e9rapie Bellefleur<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94acbf0 elementor-widget elementor-widget-text-editor\" data-id=\"94acbf0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En tant que propri\u00e9taire d&#8217;une petite entreprise au c\u0153ur de notre communaut\u00e9 depuis plus de 10 ans, je tiens \u00e0 exprimer ma sinc\u00e8re appr\u00e9ciation pour le soutien inestimable fourni par la ZAC d&#8217;Orl\u00e9ans. Son engagement in\u00e9branlable \u00e0 favoriser un environnement prosp\u00e8re pour les entreprises locales a jou\u00e9 un r\u00f4le d\u00e9terminant dans notre croissance et notre succ\u00e8s.<\/p><p>\u00a0<\/p><p>Qu&#8217;il s&#8217;agisse d&#8217;organiser des \u00e9v\u00e9nements communautaires qui attirent les visiteurs dans notre r\u00e9gion ou de fournir des ressources essentielles et des occasions de r\u00e9seautage, la ZAC apporte des initiatives qui non seulement font la promotion de nos services, mais qui cr\u00e9ent un sentiment de camaraderie parmi les entreprises locales.<\/p><p>\u00a0<\/p><p>Gr\u00e2ce \u00e0 la ZAC d&#8217;Orl\u00e9ans, nous avons constat\u00e9 une augmentation significative de l&#8217;engagement communautaire, ce qui nous a permis d&#8217;\u00e9largir notre offre et de mieux servir nos clients. Leur d\u00e9vouement \u00e0 l&#8217;am\u00e9lioration de l&#8217;\u00e9conomie locale et au soutien des petites entreprises est vraiment louable<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b272c22 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b272c22\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6134c48\" data-id=\"6134c48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f688024 elementor-widget elementor-widget-text-editor\" data-id=\"f688024\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous sommes fiers de faire partie de cette communaut\u00e9 dynamique et leur sommes reconnaissants de leur soutien constant. Ensemble, nous construisons une communaut\u00e9 plus forte et plus saine !<\/p><p>\u00a0<\/p><p>Meghan Bellefleur<\/p><p>Copropri\u00e9taire<\/p><p>&#8211;<br \/>Physioth\u00e9rapie et conditionnement physique Bellefleur<br \/>3095, boul. St-Joseph<br \/>Joseph, Orl\u00e9ans, ON<br \/>K1E 3W6<br \/>(T) 613-424-7852<br \/>[https:\/\/www.bellefleurphysio.com%20]https:\/\/www.bellefleurphysio.com<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-220167b quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"220167b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a972a70 team_user_details\" data-id=\"a972a70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-679195d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"679195d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9be2cca\" data-id=\"9be2cca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e714ec3 elementor-widget elementor-widget-video\" data-id=\"e714ec3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=Y4h1SVK5Elk&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-35b2a69\" data-id=\"35b2a69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a933ab elementor-widget elementor-widget-heading\" data-id=\"8a933ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Stuffed Cookies by Kat<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bd3e1e elementor-widget elementor-widget-text-editor\" data-id=\"4bd3e1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Deux jeunes propri\u00e9taires d&#8217;entreprise ont ouvert leur magasin dans le territoire du C\u0153ur d&#8217;Orl\u00e9ans il y a quelques mois \u00e0 peine, et nous avons \u00e9t\u00e9 gracieusement accueillis \u00e0 bras ouverts par la communaut\u00e9. La ZAC C\u0153ur d&#8217;Orl\u00e9ans a jou\u00e9 un r\u00f4le essentiel en facilitant les rencontres avec d&#8217;autres propri\u00e9taires d&#8217;entreprise de notre communaut\u00e9, en nous donnant acc\u00e8s \u00e0 des personnes qui poss\u00e8dent une grande exp\u00e9rience et des connaissances auxquelles nous n&#8217;aurions pas eu acc\u00e8s autrement. En plus de faciliter les rencontres, d&#8217;innombrables clients sont venus nous dire qu&#8217;ils avaient entendu parler de nous par le biais du bulletin d&#8217;information du BIA, ce qui a permis \u00e0 notre jeune entreprise de gagner en notori\u00e9t\u00e9 et en visibilit\u00e9. Nous sommes extr\u00eamement reconnaissants pour toute l&#8217;aide et la gentillesse que nous avons re\u00e7ues jusqu&#8217;\u00e0 pr\u00e9sent de la part de tous les b\u00e9n\u00e9voles qui travaillent dur pour la ZAC du C\u0153ur d&#8217;Orl\u00e9ans !<\/p><p>Merci beaucoup !<\/p><p>\u00a0<\/p><p>Katrina Macias<br \/>5929 Jeanne D&#8217;Arc<br \/>Orl\u00e9ans On<br \/>K1C2N1<\/p><p>\u00a0<\/p><p>https:\/\/cookiesbykat.com\/<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e9badc quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e9badc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d0d4f8f team_user_details\" data-id=\"d0d4f8f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4e4e97c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e4e97c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-41f43bb\" data-id=\"41f43bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08c3ce0 elementor-widget elementor-widget-image\" data-id=\"08c3ce0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Hobby-Hideaway__16_-May-2024-scaled-r2i8ss8el78722p1bvy6rn7hbv6tdd3srpezq4385c.jpg\" class=\"attachment-large size-large wp-image-94942\" alt=\"\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Hobby-Hideaway__16_-May-2024-scaled-r2i8ss8el78722p1bvy6rn7hbv6tdd3srpezq4385c.jpg 1024w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Hobby-Hideaway__16_-May-2024-scaled-r2i8ss8el78722p1bvy6rn7hbv6tdd3srpezq4385c-300x300.jpg 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Hobby-Hideaway__16_-May-2024-scaled-r2i8ss8el78722p1bvy6rn7hbv6tdd3srpezq4385c-150x150.jpg 150w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Hobby-Hideaway__16_-May-2024-scaled-r2i8ss8el78722p1bvy6rn7hbv6tdd3srpezq4385c-768x768.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3438dcf\" data-id=\"3438dcf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a8ade6 elementor-widget elementor-widget-heading\" data-id=\"0a8ade6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Hobby Hideaway\u200b<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-095eea6 elementor-widget elementor-widget-text-editor\" data-id=\"095eea6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En tant que nouveau propri\u00e9taire d&#8217;entreprise \u00e0 Orl\u00e9ans, je ne peux pas exprimer \u00e0 quel point je suis reconnaissant de l&#8217;accueil chaleureux et du soutien que j&#8217;ai re\u00e7u de la ZAC d&#8217;Orl\u00e9ans. D\u00e8s le d\u00e9but, ils m&#8217;ont fait sentir que je faisais partie int\u00e9grante de cette communaut\u00e9. Les \u00e9v\u00e9nements qu&#8217;ils organisent ne sont pas seulement amusants et engageants, ils sont aussi incroyablement utiles pour le r\u00e9seautage. J&#8217;ai eu l&#8217;occasion de rencontrer d&#8217;autres chefs d&#8217;entreprise, d&#8217;\u00e9changer des id\u00e9es et de nouer des relations qui ont d\u00e9j\u00e0 un impact positif sur mon activit\u00e9. Dans le mois qui a suivi l&#8217;ouverture, ils ont organis\u00e9 une interview avec un photographe pour la diffuser sur leurs m\u00e9dias sociaux et leur site web. La ZAC d&#8217;Orl\u00e9ans comprend vraiment l&#8217;importance de la communaut\u00e9, et je suis fier d&#8217;en faire partie.<\/p><p>\u00a0<\/p><p>Merci \u00e0 tous,<br \/>Jeffrey<\/p><p>\u00a0<\/p><p><strong>Jeffrey Petch<\/strong><br \/>Directeur des loisirs<\/p><p>Hobby Hideaway<br \/>(613)-983-4229<br \/>112- 1455, promenade Youville<br \/>Orl\u00e9ans, Ontario K1C 6Z7<br \/>www.hobbyhideaway.ca<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-da355c9 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da355c9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa81277 team_user_details\" data-id=\"fa81277\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-adf34b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"adf34b1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9ffd5d9\" data-id=\"9ffd5d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2841f43 elementor-widget elementor-widget-image\" data-id=\"2841f43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"475\" src=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Trilogy-Hair-Lounge__28_July-2023-768x475-1.jpg\" class=\"attachment-large size-large wp-image-94919\" alt=\"\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Trilogy-Hair-Lounge__28_July-2023-768x475-1.jpg 768w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Trilogy-Hair-Lounge__28_July-2023-768x475-1-300x186.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-09ccf17\" data-id=\"09ccf17\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29be901 elementor-widget elementor-widget-heading\" data-id=\"29be901\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Trilogy hair Lounge<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c68323 elementor-widget elementor-widget-text-editor\" data-id=\"3c68323\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Salon de coiffure Trilogy<br \/>Mich\u00e8le Amaya a \u00e9crit : \u00ab Lorsque nous avons ouvert notre nouveau salon de coiffure sur le boulevard St-Joseph, le BIA a \u00e9t\u00e9 tr\u00e8s prompt \u00e0 nous accueillir dans le quartier. Ils nous ont fait passer une entrevue et un photographe extraordinaire est venu prendre des photos de l&#8217;\u00e9quipe et de l&#8217;espace pour nous pr\u00e9senter plus tard dans leur blogue. Tout le monde a \u00e9t\u00e9 tr\u00e8s gentil et accueillant ! \u00c9tant nouveaux dans la r\u00e9gion d&#8217;Orl\u00e9ans, nous avons tout de suite senti que nous faisions partie d&#8217;une grande communaut\u00e9 !<\/p><p>\u00a0<\/p><p>Cette folle aventure a commenc\u00e9 en mars 2023, lorsque Mich\u00e8le Amaya et Kait Beauchamp r\u00eavaient d&#8217;ouvrir leur propre salon de coiffure ! Un matin, Kait a envoy\u00e9 \u00e0 Mich\u00e8le une liste de locaux \u00e0 louer \u00e0 Orl\u00e9ans et cela semblait trop beau pour \u00eatre vrai !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ae651b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ae651b7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-355bab4\" data-id=\"355bab4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdaa5aa elementor-widget elementor-widget-text-editor\" data-id=\"cdaa5aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il a suffi d&#8217;une visite pour qu&#8217;elles tombent amoureuses. Elles ont contact\u00e9 leur ch\u00e8re amie Raeanne Edgley, qui est une artiste capillaire extraordinaire, et se sont mises directement au travail. Leur mission \u00e9tait d&#8217;ouvrir un salon de coiffure chaleureux, relaxant et accueillant pour tous.<\/p><p>\u00a0<\/p><p>Le nom \u00ab Trilogy Hair Lounge \u00bb vient d&#8217;une discussion de groupe que les trois femmes ont eue et qui s&#8217;appelait \u00ab dynamic trio \u00bb, alors elles ont jou\u00e9 sur le mot trio et sont arriv\u00e9es \u00e0 Trilogy. Ce sont trois femmes qui partagent le m\u00eame amour et la m\u00eame passion pour l&#8217;industrie et le travail avec les gens.<\/p><p>\u00a0<\/p><p>Trilogy Hair Lounge<\/p><p>2208, boulevard St-Joseph<\/p><p>Joseph, t\u00e9l. : 613.837.3733<\/p><p>Trilogylounce.ca<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-048730b quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"048730b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ac98987 team_user_details\" data-id=\"ac98987\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8e434ec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8e434ec\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0a76742\" data-id=\"0a76742\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eced86d elementor-widget elementor-widget-image\" data-id=\"eced86d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/cafe-amore3-r2i8slnj9cz6ssyleb3ss6v96638vhdoesuld6czcw.jpg\" class=\"attachment-large size-large wp-image-94944\" alt=\"\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/cafe-amore3-r2i8slnj9cz6ssyleb3ss6v96638vhdoesuld6czcw.jpg 1024w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/cafe-amore3-r2i8slnj9cz6ssyleb3ss6v96638vhdoesuld6czcw-300x300.jpg 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/cafe-amore3-r2i8slnj9cz6ssyleb3ss6v96638vhdoesuld6czcw-150x150.jpg 150w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/cafe-amore3-r2i8slnj9cz6ssyleb3ss6v96638vhdoesuld6czcw-768x768.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-15d9b7e\" data-id=\"15d9b7e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a4f190 elementor-widget elementor-widget-heading\" data-id=\"7a4f190\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Caf\u00e9 Amore\u200b<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b74095b elementor-widget elementor-widget-text-editor\" data-id=\"b74095b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>J&#8217;aimerais prendre le temps de vous exprimer ma gratitude \u00e0 tous pour le service, les conseils et le soutien extraordinaires que vous offrez \u00e0 toutes les petites entreprises du c\u0153ur d&#8217;Orl\u00e9ans.<\/p><p>\u00a0<\/p><p>En tant que propri\u00e9taire du Caf\u00e9 Amore, j&#8217;appr\u00e9cie sinc\u00e8rement tout ce que vous faites pour nous et ce depuis le premier jour : mai 2023. Vous avez fait notre promotion et partag\u00e9 nos articles \u00e0 de nombreuses reprises via les m\u00e9dias sociaux et le bouche-\u00e0-oreille. Vous nous encouragez toujours \u00e0 participer \u00e0 vos ateliers de r\u00e9seautage pour rencontrer d&#8217;autres entreprises d&#8217;Orl\u00e9ans &#8211; quelle id\u00e9e g\u00e9niale ! Vous nous permettez d&#8217;ajouter un blog dans votre lettre d&#8217;information mensuelle. Je dois dire que nous sommes vraiment b\u00e9nis et reconnaissants.<\/p><p>\u00a0<\/p><p>Vous \u00eates les meilleurs !<\/p><p>\u00a0<\/p><p>Avec tout mon amour et mes remerciements<\/p><p>Emma Cosentino<\/p><p>Propri\u00e9taire du Caf\u00e9 Amore<\/p><p>2425, boulevard St-Joseph<\/p><p>613-841-5005<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c9df1eb quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c9df1eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d585687 team_user_details\" data-id=\"d585687\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-13a6201 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13a6201\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b8e84ef\" data-id=\"b8e84ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cdc952 elementor-widget elementor-widget-image\" data-id=\"3cdc952\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Gutsies-__27_July-2023-1400x1400-1-1024x1024.jpg\" class=\"attachment-large size-large wp-image-94946\" alt=\"\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Gutsies-__27_July-2023-1400x1400-1-1024x1024.jpg 1024w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Gutsies-__27_July-2023-1400x1400-1-300x300.jpg 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Gutsies-__27_July-2023-1400x1400-1-150x150.jpg 150w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Gutsies-__27_July-2023-1400x1400-1-768x768.jpg 768w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Gutsies-__27_July-2023-1400x1400-1-1200x1200.jpg 1200w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Gutsies-__27_July-2023-1400x1400-1.jpg 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2bdd315\" data-id=\"2bdd315\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb7bb1b elementor-widget elementor-widget-heading\" data-id=\"cb7bb1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Gutsies<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-054dd1c elementor-widget elementor-widget-text-editor\" data-id=\"054dd1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En d\u00e9cembre 2022, Natasha Landry et Denis Ouellet ont ouvert Gutsies, une \u00e9picerie et une boulangerie 100 % sans gluten. Le magasin a ouvert ses portes et la communaut\u00e9 les a accueillis \u00e0 bras ouverts. Ils vendent des produits de boulangerie frais et offrent de nombreux produits sans gluten de Montr\u00e9al et de Toronto, ainsi que des soupes et des plats pr\u00e9par\u00e9s. La p\u00e2te \u00e0 pizza surgel\u00e9e est l&#8217;une des meilleures de la ville. Le pain au chocolat matinal est \u00e0 essayer absolument, de m\u00eame que les muffins \u00e0 la banane, tout simplement d\u00e9cadents.<\/p><p>\u00a0<\/p><p>Selon les propres mots de Natasha : &#8220;Lorsque nous avons choisi l&#8217;emplacement de notre petite entreprise familiale, nous cherchions un endroit pratique pour les clients venant de pr\u00e8s ou de loin, pr\u00e8s de l&#8217;autoroute, dans une partie d&#8217;Orl\u00e9ans qui se sentait comme une communaut\u00e9. Nous avons fait le bon choix. Les visages des membres de la BIA ont \u00e9t\u00e9 parmi les premiers que nous avons vus, ils \u00e9taient l\u00e0 pour offrir des services, du soutien et des ressources, tout comme le nouveau venu. Depuis ce jour, il est clair qu&#8217;ils sont l\u00e0 pour r\u00e9pondre aux besoins de chaque entreprise et de chaque communaut\u00e9 qu&#8217;ils servent. Ils vous accueillent \u00e0 bras ouverts et vous souhaitent vraiment la bienvenue dans la famille Heart of Orleans.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cfdf580 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cfdf580\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-50b8d53\" data-id=\"50b8d53\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb08dac elementor-widget elementor-widget-text-editor\" data-id=\"fb08dac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Peu importe ce que votre entreprise a \u00e0 offrir, ils font tout leur possible pour promouvoir vos services et les utiliser pour eux-m\u00eames, lorsque c&#8217;est possible, tout en encourageant sinc\u00e8rement votre r\u00e9ussite. Ils sont \u00e9galement un pont entre les petites boutiques et les entit\u00e9s gouvernementales plus importantes, pr\u00e9sents \u00e0 tous les \u00e9v\u00e9nements, nous tenant au courant. Comme tous les chefs d&#8217;entreprise, la ZAC d&#8217;Orl\u00e9ans est fi\u00e8re du sentiment de communaut\u00e9 qu&#8217;elle cr\u00e9e, du r\u00e9seau offert et des relations qui naissent de sa pr\u00e9sence, de son caract\u00e8re inclusif. Merci pour tout ce que vous faites !<\/p><p>\u00a0<\/p><p>Natasha Landry et Denis Ouellet Propri\u00e9taires<br \/>2297, boul. St-Joseph<br \/>Orl\u00e9ans On<br \/>613.355.8194<br \/>Gutsies.ca<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a246b5e quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a246b5e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9c8ad72 team_user_details\" data-id=\"9c8ad72\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e9e7e5a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e9e7e5a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3fa06e9\" data-id=\"3fa06e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-92b9968 elementor-widget elementor-widget-image\" data-id=\"92b9968\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Pure-Holistic-__12_November-2023-scaled-r2i8y4xbi8jz64x52p8pgskz3ut27bcru75j3u5ips.jpg\" class=\"attachment-large size-large wp-image-94948\" alt=\"\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Pure-Holistic-__12_November-2023-scaled-r2i8y4xbi8jz64x52p8pgskz3ut27bcru75j3u5ips.jpg 1024w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Pure-Holistic-__12_November-2023-scaled-r2i8y4xbi8jz64x52p8pgskz3ut27bcru75j3u5ips-300x300.jpg 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Pure-Holistic-__12_November-2023-scaled-r2i8y4xbi8jz64x52p8pgskz3ut27bcru75j3u5ips-150x150.jpg 150w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Pure-Holistic-__12_November-2023-scaled-r2i8y4xbi8jz64x52p8pgskz3ut27bcru75j3u5ips-768x768.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1fa9a16\" data-id=\"1fa9a16\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e48f24d elementor-widget elementor-widget-heading\" data-id=\"e48f24d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pure Holistic<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08bc01e elementor-widget elementor-widget-text-editor\" data-id=\"08bc01e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En 2019, Kamouraska Cote a d\u00e9cid\u00e9 d&#8217;ouvrir PURE Holistic situ\u00e9 au 1803 St Joseph Blvd. PURE Holistic est un centre de bien-\u00eatre con\u00e7u pour gu\u00e9rir et rajeunir l&#8217;esprit et le corps. L&#8217;objectif est d&#8217;aider le plus grand nombre de personnes possible \u00e0 avoir une vie plus saine et plus longue en offrant des alternatives naturelles pour garder le syst\u00e8me immunitaire fort et r\u00e9sistant.<\/p><p>\u00a0<\/p><p>Kamy a v\u00e9cu \u00e0 Orl\u00e9ans la majeure partie de sa vie. Elle appr\u00e9cie le sens de la communaut\u00e9 et l&#8217;aspect bilingue de la ville.\u202f Si vous ne la trouvez pas au centre de bien-\u00eatre, vous la trouverez probablement en train de danser une temp\u00eate de salsa ou de faire une longue promenade &#8211; surtout dans la neige par une journ\u00e9e d&#8217;hiver fra\u00eeche et ensoleill\u00e9e.<\/p><p>\u00a0<\/p><p>PURE Holistic Health and Wellness ouvrira ses portes en 2019. La ZAC du C\u0153ur d&#8217;Orl\u00e9ans a \u00e9t\u00e9 un pilier de soutien pour notre entreprise. Gr\u00e2ce \u00e0 son d\u00e9vouement in\u00e9branlable et \u00e0 ses diverses initiatives, elle nous a mis en contact avec d&#8217;autres entreprises, nous a tenus au courant des \u00e9v\u00e9nements locaux et nous a fourni des mises \u00e0 jour cruciales sur le paysage en constante \u00e9volution de notre communaut\u00e9. Ce fut un plaisir de communiquer avec le personnel de la ZAC d&#8217;Orl\u00e9ans qui est toujours l\u00e0 pour nous aider \u00e0 d\u00e9velopper notre entreprise dans cette communaut\u00e9.<\/p><p>\u00a0<\/p><p>Pure Holistic<\/p><p>1803 St Joseph Blvd Unit 17, Orl\u00e9ans, ON, K1C 6E7<\/p><p>(613)261-4233<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-226b293 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"226b293\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-51cb898 team_user_details\" data-id=\"51cb898\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1cb568d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1cb568d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5b31be2\" data-id=\"5b31be2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c50c030 elementor-widget elementor-widget-image\" data-id=\"c50c030\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"639\" src=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Pace-E-Bike-__4_March-2024-1-1400x874-1-1024x639.jpg\" class=\"attachment-large size-large wp-image-94950\" alt=\"\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Pace-E-Bike-__4_March-2024-1-1400x874-1-1024x639.jpg 1024w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Pace-E-Bike-__4_March-2024-1-1400x874-1-300x187.jpg 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Pace-E-Bike-__4_March-2024-1-1400x874-1-768x479.jpg 768w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Pace-E-Bike-__4_March-2024-1-1400x874-1-1200x749.jpg 1200w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/Pace-E-Bike-__4_March-2024-1-1400x874-1.jpg 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9d1cfc0\" data-id=\"9d1cfc0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9053ff9 elementor-widget elementor-widget-heading\" data-id=\"9053ff9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pace<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8aee5d0 elementor-widget elementor-widget-text-editor\" data-id=\"8aee5d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Daniel Robinson, propri\u00e9taire de Pace- Electrify your leisure, a d\u00e9cid\u00e9 d&#8217;ouvrir son nouveau magasin de v\u00e9los \u00e9lectriques sur le boulevard Saint-Joseph, au c\u0153ur d&#8217;Orl\u00e9ans, en 2023<\/p><p>L&#8217;id\u00e9e lui est venue lorsqu&#8217;il a ressenti le besoin de participer \u00e0 l&#8217;\u00e9cologisation du monde. Sa mission est de fournir une alternative \u00e9lectrique pour tous les aspects du voyage et des loisirs. Son entreprise aide \u00e0 contrer les co\u00fbts et les effets environnementaux de l&#8217;essence. \u00c0 l&#8217;heure actuelle, il emploie trois personnes pour l&#8217;aider \u00e0 concr\u00e9tiser sa vision.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1df9e80 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1df9e80\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-03a2ff2\" data-id=\"03a2ff2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9dc8c30 elementor-widget elementor-widget-text-editor\" data-id=\"9dc8c30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ce que Daniel pr\u00e9f\u00e8re dans son activit\u00e9, c&#8217;est la possibilit\u00e9 d&#8217;offrir des produits de qualit\u00e9 et un service \u00e0 la client\u00e8le exceptionnel. Il propose \u00e0 ses clients la vente, la mise au point, la r\u00e9paration et l&#8217;entretien de v\u00e9los \u00e9lectriques, mais se sp\u00e9cialise \u00e9galement dans d&#8217;autres produits li\u00e9s aux loisirs \u00e9lectriques, tels que les scooters et les accessoires. Daniel comprend que la sensibilisation, la coh\u00e9rence et la familiarit\u00e9 favorisent naturellement la confiance. Il se souvient toujours de garder ses valeurs authentiques au c\u0153ur de sa marque, ce qui permet \u00e0 ses clients de revenir. &#8211;<\/p><p>\u00a0<\/p><p>Nous aimons faire partie de la communaut\u00e9 et aider les gens avec nos services. Le BIA, tout comme nous, accorde de l&#8217;importance aux relations personnelles et \u00e0 l&#8217;excellence du service qui permettent \u00e0 une entreprise de se d\u00e9marquer. Le BIA est l&#8217;endroit de choix pour aider \u00e0 la croissance de votre entreprise et pour atteindre la communaut\u00e9.<\/p><p>\u00a0<\/p><p>Daniel Robinson<\/p><p>Pace-Electrify your leisure <br \/>2454, boul. St-Joseph, Orl\u00e9ans <br \/>613-841-9090 <br \/>www.paceebike.ca<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31db989 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31db989\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-090a49b team_user_details\" data-id=\"090a49b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-27c8083 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"27c8083\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1352ec7\" data-id=\"1352ec7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96f95f4 elementor-widget elementor-widget-image\" data-id=\"96f95f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"554\" src=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/f6805750-897b-44f5-b228-63cef2cbda52-1400x758-1-1024x554.jpeg\" class=\"attachment-large size-large wp-image-94952\" alt=\"\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/f6805750-897b-44f5-b228-63cef2cbda52-1400x758-1-1024x554.jpeg 1024w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/f6805750-897b-44f5-b228-63cef2cbda52-1400x758-1-300x162.jpeg 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/f6805750-897b-44f5-b228-63cef2cbda52-1400x758-1-768x416.jpeg 768w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/f6805750-897b-44f5-b228-63cef2cbda52-1400x758-1-1200x650.jpeg 1200w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/05\/f6805750-897b-44f5-b228-63cef2cbda52-1400x758-1.jpeg 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8c34721\" data-id=\"8c34721\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3416885 elementor-widget elementor-widget-heading\" data-id=\"3416885\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Dogtopia<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86ebc87 elementor-widget elementor-widget-text-editor\" data-id=\"86ebc87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nisso Ifrah est le propri\u00e9taire de Dogtopia\u00a0<\/p><p>\u00a0<\/p><p>Dogtopia est la principale destination pour les services de garderie, de pension et de spa pour chiens. Sa mission est de s&#8217;assurer que les membres de votre famille \u00e0 quatre pattes sont en s\u00e9curit\u00e9 et qu&#8217;ils s&#8217;amusent lorsqu&#8217;ils sont dans ses installations modernes \u00e0 aire ouverte.<\/p><p>\u00a0<\/p><p>Chez Dogtopia, votre chien fait partie de la famille. Dogtopia lui offre un espace s\u00fbr o\u00f9 il peut se socialiser et rencontrer d&#8217;autres chiens. Si vous \u00eates occup\u00e9 et que vous ne pouvez pas promener votre chien, Dogtopia est con\u00e7u comme l&#8217;endroit id\u00e9al pour faire faire de l&#8217;exercice \u00e0 votre chien dans un environnement s\u00fbr et amical. La s\u00e9curit\u00e9 de votre chien est leur priorit\u00e9 absolue ; c&#8217;est pourquoi la formation de leur \u00e9quipe est certifi\u00e9e par deux associations nationales reconnues dans le domaine du comportement canin<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-589af9d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"589af9d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b803eec\" data-id=\"b803eec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9251d4e elementor-widget elementor-widget-text-editor\" data-id=\"9251d4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dogtopia compte 25 employ\u00e9s, qui suivent tous un programme de formation approfondi. Les salles de jeux sont supervis\u00e9es par ces entra\u00eeneurs canins certifi\u00e9s, et votre chien sera dans une salle de jeux o\u00f9 il sera entour\u00e9 de chiens de taille, de temp\u00e9rament et de style de jeu similaires, ainsi que de chiens enti\u00e8rement vaccin\u00e9s et ayant pass\u00e9 avec succ\u00e8s l&#8217;\u00e9valuation de Dogtopia. Votre chien sera entre de tr\u00e8s bonnes mains pendant son s\u00e9jour chez eux !<\/p><p>\u00a0<\/p><p>Le mot de Nisso Ifrah : Nous avons ouvert notre garderie \u00e0 Orl\u00e9ans en d\u00e9cembre 2023. Heart of Orleans nous a beaucoup aid\u00e9s \u00e0 nous impliquer dans la communaut\u00e9.\u202f Rita nous a particuli\u00e8rement aid\u00e9s \u00e0 trouver un photographe pour notre inauguration.\u202f<\/p><p>\u00a0<\/p><p>Nisso Ifrah<\/p><p>1224 Place D\u2019Orl\u00e9ans Dr, Unit 111A. Orl\u00e9ans On, K1C7K3\u00a0<\/p><p>Tel:613.801.1500<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64d176e quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"64d176e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7bced13 team_user_details\" data-id=\"7bced13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3d369c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d369c4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dce9413\" data-id=\"dce9413\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa6af49 elementor-widget elementor-widget-video\" data-id=\"aa6af49\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/-6oOdXj4M3s&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5aa8d45\" data-id=\"5aa8d45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-298d2fb elementor-widget elementor-widget-heading\" data-id=\"298d2fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Bookkeeping Bureau<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-355f968 elementor-widget elementor-widget-text-editor\" data-id=\"355f968\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Todd Muise, chef de l&#8217;exploitation<\/p><p>&#8220;La ZAC a jou\u00e9 un r\u00f4le fantastique dans notre entreprise. Elle nous a permis de nous faire de nouveaux amis, des voisins dans la communaut\u00e9, de reconna\u00eetre des occasions d&#8217;affaires gr\u00e2ce \u00e0 des \u00e9v\u00e9nements de r\u00e9seautage, d&#8217;interagir avec divers paliers de gouvernement, d&#8217;\u00eatre au courant de programmes et d&#8217;initiatives r\u00e9cents dont nous n&#8217;aurions peut-\u00eatre pas eu connaissance autrement, et enfin, elle a donn\u00e9 \u00e0 notre \u00e9quipe l&#8217;occasion de faire du b\u00e9n\u00e9volat et d&#8217;interagir dans notre communaut\u00e9 \u00e0 un niveau qui ne leur est pas habituellement offert, et nous avons vu l&#8217;impact qui s&#8217;est produit. Nous sommes vraiment fiers de faire partie de<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6fa230e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6fa230e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-95069d9\" data-id=\"95069d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75b0511 elementor-widget elementor-widget-text-editor\" data-id=\"75b0511\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>la communaut\u00e9 d&#8217;Orl\u00e9ans et la ZAC. Je ne comprends pas pourquoi quelqu&#8217;un ne voudrait pas faire partie de la ZAC.<\/p><p>\u00a0<\/p><p>En r\u00e9alit\u00e9, les affaires sont une affaire de communaut\u00e9. Il s&#8217;agit de se faire des clients. Il s&#8217;agit de cr\u00e9er du bouche \u00e0 oreille, de cr\u00e9er de la confiance, de trouver de nouvelles opportunit\u00e9s. La ZAC est vraiment une communaut\u00e9 d&#8217;entreprises et lorsque vous en faites partie, vous pouvez vous appuyer sur toutes les autres entreprises pour les aider \u00e0 se d\u00e9velopper et \u00e0 d\u00e9velopper les leurs. Pour moi, c&#8217;est une \u00e9vidence ! Tout le monde devrait faire partie de la ZAC. Ce qui m&#8217;a le plus surpris en tant que membre de la BIA, c&#8217;est que cela m&#8217;a donn\u00e9 plus d&#8217;\u00e9nergie que cela ne m&#8217;en a pris. Lorsque j&#8217;ai commenc\u00e9 \u00e0 faire partie de la ZAC, je pensais que c&#8217;\u00e9tait un endroit o\u00f9 je mettrais mon \u00e9nergie, mais maintenant je trouve qu&#8217;apr\u00e8s nos r\u00e9unions, apr\u00e8s nos \u00e9v\u00e9nements de r\u00e9seautage, apr\u00e8s avoir re\u00e7u le dernier exemplaire de The Beat, je suis enthousiaste au sujet de ma communaut\u00e9, je suis enthousiaste au sujet de ce qui se passe, et je veux juste trouver un moyen d&#8217;en faire plus.<\/p><p>\u00a0<\/p><p>Je d\u00e9crirais la ZAC comme une &#8220;communaut\u00e9&#8221;. La ZAC a vraiment jou\u00e9 un r\u00f4le important pendant la pand\u00e9mie. Une grande partie de la communaut\u00e9 d&#8217;affaires d&#8217;Orl\u00e9ans se tournait vers la ZAC pour obtenir des avis \u00e0 jour sur les fermetures li\u00e9es \u00e0 la pand\u00e9mie, sur les mesures de sant\u00e9 et de s\u00e9curit\u00e9 et sur ce que faisaient les autres entreprises. C&#8217;\u00e9tait un endroit id\u00e9al pour obtenir des informations de la part de nos repr\u00e9sentants \u00e9lus et lorsque nous avons pass\u00e9 plus de temps \u00e0 la maison et que nous avons eu l&#8217;impression de ne pas avoir la possibilit\u00e9 d&#8217;interagir avec d&#8217;autres entreprises, la ZAC du C\u0153ur d&#8217;Orl\u00e9ans nous a donn\u00e9 la chance de nous r\u00e9unir dans un forum pour partager des id\u00e9es, partager des d\u00e9fis et nous soutenir les uns les autres. Je recommanderais certainement la ZAC.<\/p><p>\u00a0<\/p><p>Todd Muise, COO Bookkeeping Bureau<\/p><p>2618, boul. St-Joseph, bureau 200, Ottawa, ON K1C 1G3<\/p><p>(613) 424-1101<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f433ef quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f433ef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5543df5 team_user_details\" data-id=\"5543df5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2c7dc9e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c7dc9e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a57645b\" data-id=\"a57645b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0c994b elementor-widget elementor-widget-video\" data-id=\"d0c994b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/ejBKkfNMC3Q&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3ab1129\" data-id=\"3ab1129\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f63f3a elementor-widget elementor-widget-heading\" data-id=\"3f63f3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Stray Dog Brewing Company<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63b650c elementor-widget elementor-widget-text-editor\" data-id=\"63b650c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Marc Plante, copropri\u00e9taire<\/p><p>&#8220;L&#8217;importance de la ZAC r\u00e9side dans la communaut\u00e9 &#8211; et non seulement dans le fait de rassembler les gens, mais aussi les petites entreprises. Une mar\u00e9e montante soul\u00e8ve tous les bateaux et la ZAC offre vraiment cela \u00e0 toutes les petites entreprises &#8211; non seulement pour se connecter les unes aux autres, mais aussi pour se connecter \u00e0 la communaut\u00e9. Ce que j&#8217;aime le plus dans la BIA, ce sont les liens que nous \u00e9tablissons avec d&#8217;autres propri\u00e9taires d&#8217;entreprises. Nous pouvons partager nos succ\u00e8s et nos \u00e9checs. Nous pouvons apprendre les uns des autres et nous soutenir en m\u00eame temps. Je recommanderais certainement le BIA \u00e0 d&#8217;autres entreprises.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9564b19 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9564b19\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5d22875\" data-id=\"5d22875\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38ce5fe elementor-widget elementor-widget-text-editor\" data-id=\"38ce5fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous sommes plus forts en travaillant ensemble qu&#8217;en travaillant s\u00e9par\u00e9ment. On ne sait jamais ce qu&#8217;une autre entreprise peut offrir \u00e0 la sienne. Pendant la pand\u00e9mie, la BIA a jou\u00e9 un r\u00f4le d\u00e9terminant dans notre survie, si l&#8217;on peut dire. Non seulement elle nous a offert des outils et des ressources formidables pour traverser cette p\u00e9riode difficile, mais elle nous a \u00e9galement propos\u00e9 de nombreux liens vers des subventions et des financements disponibles pour les petites entreprises, dont nous n&#8217;aurions peut-\u00eatre pas eu connaissance autrement. Le BIA, c&#8217;est la communaut\u00e9 &#8211; le fil conducteur qui nous unit tous.<\/p><p>\u00a0<\/p><p>Marc Plante, copropri\u00e9taire Stray Dog Brewing Company<\/p><p>501 Lacolle Way Unit 4, Orl\u00e9ans, ON K4A 5B6<\/p><p>(613) 830-7364<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac557ba quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ac557ba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de049e6 team_user_details\" data-id=\"de049e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5b07b05 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b07b05\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7c592ff\" data-id=\"7c592ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-303d822 elementor-widget elementor-widget-video\" data-id=\"303d822\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/fS9ckI_St3U&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6e960e4\" data-id=\"6e960e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e17202 elementor-widget elementor-widget-heading\" data-id=\"4e17202\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Modo Yoga Orl\u00e9ans<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9877917 elementor-widget elementor-widget-text-editor\" data-id=\"9877917\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Julie Pangilinan, copropri\u00e9taire<\/p><p>\u00a0<\/p><p>&#8220;La ZAC du C\u0153ur d&#8217;Orl\u00e9ans a aid\u00e9 notre entreprise gr\u00e2ce \u00e0 son soutien constant, \u00e0 diverses initiatives telles que des rencontres et des liens avec d&#8217;autres entreprises et en nous informant de ce qui se passe dans la rue. Il est tr\u00e8s important de savoir ce qui se passe et j&#8217;appr\u00e9cie vraiment de recevoir leurs courriels. Je le marque pour pouvoir le lire plus tard, quand j&#8217;aurai plus de temps, parce que l&#8217;information fournie est vraiment bonne. Des choses comme les nouvelles entreprises, des mises \u00e0 jour sur le TLR, des incitations gouvernementales &#8211; beaucoup d&#8217;informations r\u00e9unies dans un seul courriel. Nous sommes ouverts aujourd&#8217;hui gr\u00e2ce au soutien qui nous a \u00e9t\u00e9 apport\u00e9 pendant la pand\u00e9mie. Les entreprises familiales font d&#8217;Orl\u00e9ans un endroit unique et nous sommes en plein milieu ! Je donne \u00e0 la ZAC une note de 10 sur 10 !&#8221;<\/p><p>\u00a0<\/p><p>Julie Pangilinan, copropri\u00e9taire Modo Yoga Orl\u00e9ans<\/p><p>2442, boul. St-Joseph, Orl\u00e9ans, ON K1C 1G1<\/p><p>(613) 424-8221<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0844cd1 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0844cd1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d58b138 team_user_details\" data-id=\"d58b138\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9df0ca8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9df0ca8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b38a59f\" data-id=\"b38a59f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55dac8f elementor-widget elementor-widget-video\" data-id=\"55dac8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=nAroGpH3VFo&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ff3a9c3\" data-id=\"ff3a9c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8a6020 elementor-widget elementor-widget-heading\" data-id=\"a8a6020\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ace Arte Studio<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b60bc9 elementor-widget elementor-widget-text-editor\" data-id=\"1b60bc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Steffi Acevedo, propri\u00e9taire<\/p><p>&#8220;En tant que nouveau propri\u00e9taire d&#8217;entreprise, d\u00e8s que j&#8217;ai ouvert, j&#8217;ai contact\u00e9 le BIA. J&#8217;ai trouv\u00e9 qu&#8217;il \u00e9tait tr\u00e8s utile d&#8217;entrer en contact avec d&#8217;autres propri\u00e9taires d&#8217;entreprises et avec des ressources qui m&#8217;aideraient \u00e0 promouvoir ma nouvelle entreprise et \u00e0 \u00e9largir mon public. Ils ont \u00e9t\u00e9 formidables pour promouvoir mes cours et mon activit\u00e9 cr\u00e9ative. J&#8217;ai trouv\u00e9 tr\u00e8s agr\u00e9able d&#8217;entrer en contact avec d&#8217;autres propri\u00e9taires d&#8217;entreprises locales pour voir \u00e0 quoi ressemblait la communaut\u00e9. J&#8217;habite \u00e0 Orl\u00e9ans depuis environ six ans, mais j&#8217;avais l&#8217;impression d&#8217;\u00eatre relativement nouvelle dans la r\u00e9gion. Le fait d&#8217;apprendre \u00e0 conna\u00eetre mon public et la communaut\u00e9 m&#8217;a \u00e9t\u00e9 tr\u00e8s utile gr\u00e2ce \u00e0 la ZAC.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bf44a41 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf44a41\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0f287b5\" data-id=\"0f287b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af8aa43 elementor-widget elementor-widget-text-editor\" data-id=\"af8aa43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>C&#8217;est le d\u00e9partement marketing qui m&#8217;a demand\u00e9 de rejoindre la ZAC. Je pense qu&#8217;ils cherchaient quelqu&#8217;un de cr\u00e9atif, qui aurait de nouvelles id\u00e9es pour promouvoir la ZAC. Je suis donc heureuse de faire partie de leurs projets existants et de leurs nouveaux projets pour aider la communaut\u00e9 d&#8217;Orl\u00e9ans et faire cro\u00eetre d&#8217;autres entreprises.<\/p><p>\u00a0<\/p><p>Ce que j&#8217;aime le plus dans la ZAC, c&#8217;est qu&#8217;elle est tr\u00e8s accessible parce qu&#8217;elle est compos\u00e9e d&#8217;autres propri\u00e9taires de petites entreprises. Certains d&#8217;entre eux sont en affaires depuis de nombreuses ann\u00e9es et d&#8217;autres sont tout nouveaux, comme moi. Lorsque nous cherchons des mises \u00e0 jour sur le TLR ou des possibilit\u00e9s de subventions, il est tr\u00e8s facile de discuter avec eux. Ce qui m&#8217;a surpris, c&#8217;est leur capacit\u00e9 \u00e0 promouvoir tous les membres de la BIA. Chaque fois que j&#8217;organise un \u00e9v\u00e9nement, un cours ou autre chose, je n&#8217;ai qu&#8217;\u00e0 les \u00e9tiqueter et ils sont ravis de partager leurs informations. Beaucoup d&#8217;\u00e9tudiants et de clients ont franchi mes portes parce qu&#8217;ils ont entendu parler de mon entreprise par l&#8217;interm\u00e9diaire de la BIA.<\/p><p>\u00a0<\/p><p>Je recommanderais \u00e0 100 % la BIA \u00e0 d&#8217;autres petites entreprises. Comme je l&#8217;ai dit, elle est compos\u00e9e de propri\u00e9taires d&#8217;entreprises qui en sont \u00e0 diff\u00e9rentes \u00e9tapes de leur cheminement, alors c&#8217;est vraiment formidable d&#8217;aider ceux qui commencent et d&#8217;apprendre de ceux qui sont en affaires depuis longtemps. C&#8217;est une communaut\u00e9 vraiment formidable \u00e0 Orl\u00e9ans et c&#8217;est agr\u00e9able de pouvoir discuter avec d&#8217;autres pairs.<\/p><p>\u00a0<\/p><p>Nous avons obtenu cet espace \u00e0 la p\u00e9riode de No\u00ebl, vers janvier ou f\u00e9vrier. Je me concentrais encore sur la construction de l&#8217;espace, et je n&#8217;avais donc pas encore contact\u00e9 la BIA. C&#8217;est lorsque j&#8217;ai commenc\u00e9 \u00e0 pr\u00e9parer ma programmation que j&#8217;ai pris contact avec eux. C&#8217;\u00e9tait une p\u00e9riode d\u00e9licate parce qu&#8217;il n&#8217;y avait pas de date limite et je sais qu&#8217;il se passe encore beaucoup de choses, mais je savais qu&#8217;ils me soutenaient, que je doive faire pivoter mon plan d&#8217;affaires pour enseigner de mani\u00e8re plus priv\u00e9e, ce qui \u00e9tait ma deuxi\u00e8me option, ou utiliser ce grand espace ouvert pour enseigner aux gens de mani\u00e8re individuelle ou en tr\u00e8s petits groupes. La BIA, d\u00e8s qu&#8217;elle a appris qu&#8217;il y avait une nouvelle entreprise et qu&#8217;il s&#8217;agissait d&#8217;une entreprise cr\u00e9ative, s&#8217;est empress\u00e9e de m&#8217;aider \u00e0 me d\u00e9velopper. Je pense qu&#8217;\u00e0 cause de la pand\u00e9mie, les gens ont vraiment envie de se reconnecter et de gu\u00e9rir par l&#8217;art, et j&#8217;ai une formation d&#8217;art-th\u00e9rapeute, alors j&#8217;\u00e9tais heureuse de pouvoir offrir ce service aux gens de la communaut\u00e9.<\/p><p>\u00a0<\/p><p>Steffi Acevedo, propri\u00e9taire de Ace Arte Studio<\/p><p>2095 St Joseph Blvd Unit 1, Orl\u00e9ans ON, K1C 1C5<\/p><p>(613) 590-1010<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3578599 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3578599\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bb6badb team_user_details\" data-id=\"bb6badb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7899c1e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7899c1e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-094e219\" data-id=\"094e219\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79bba61 elementor-widget elementor-widget-video\" data-id=\"79bba61\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=A15vR38j39s&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9195e1c\" data-id=\"9195e1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7944172 elementor-widget elementor-widget-heading\" data-id=\"7944172\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Art of Bean Coffee Co.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71191f3 elementor-widget elementor-widget-text-editor\" data-id=\"71191f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Elizabeth Iverson, Co-propri\u00e9taire<\/p><p>La ZAC nous a beaucoup aid\u00e9s en tant que nouveaux propri\u00e9taires d&#8217;entreprise dans cette communaut\u00e9. Comme nous ne connaissions que les gens de notre entourage imm\u00e9diat, avec l&#8217;\u00e9cole de musique et la galerie d&#8217;art, c&#8217;\u00e9tait un tr\u00e8s bon moyen pour nous d&#8217;entrer en contact avec d&#8217;autres propri\u00e9taires d&#8217;entreprises et m\u00eame avec un public plus large d&#8217;habitants d&#8217;Orl\u00e9ans. Ils nous ont affich\u00e9s sur leurs m\u00e9dias sociaux, nous avons particip\u00e9 \u00e0 des \u00e9v\u00e9nements de r\u00e9seautage et nous avons rencontr\u00e9 des gens vraiment formidables au sein de la communaut\u00e9 des affaires et de la communaut\u00e9 dans laquelle nous nous trouvons actuellement.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-29509e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29509e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-10bb669\" data-id=\"10bb669\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d21259d elementor-widget elementor-widget-text-editor\" data-id=\"d21259d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ce que j&#8217;aime le plus de la ZAC, c&#8217;est le sens de la communaut\u00e9 et le fait de savoir que vous avez un groupe de personnes qui vous soutiennent et qui veillent aux meilleurs int\u00e9r\u00eats d&#8217;Orl\u00e9ans. Savoir qu&#8217;il y a des gens qui travaillent \u00e0 apporter des changements positifs et \u00e0 collaborer, c&#8217;est se sentir beaucoup mieux accueilli et je pense que cela se transmet aussi aux gens qui vivent ici, qu&#8217;il y a un groupe de personnes qui travaillent activement et tr\u00e8s fort pour enrichir les espaces et pour soutenir les entreprises locales.<\/p><p>\u00a0<\/p><p>Pour ce qui est de la sortie de la pand\u00e9mie, la ZAC a tr\u00e8s bien su afficher et nous faire savoir ce qui se passait dans la communaut\u00e9 en termes d&#8217;ouverture et de fermeture, de ce qui \u00e9tait autoris\u00e9 et de ce qui ne l&#8217;\u00e9tait pas, ce qui nous a \u00e9t\u00e9 utile lorsque nous \u00e9tions encore en train de naviguer en tant que nouvelle entreprise et toutes les r\u00e8gles li\u00e9es \u00e0 l&#8217;ouverture et \u00e0 la fermeture alors que les choses se passaient encore activement avec les protocoles de pand\u00e9mie.<\/p><p>\u00a0<\/p><p>Le mot que j&#8217;emploierais pour d\u00e9crire la BIA est &#8220;accueillant&#8221;. C&#8217;est ce que nous avons ressenti d\u00e8s notre ouverture, lorsqu&#8217;ils sont venus pour la premi\u00e8re fois nous dire qui ils \u00e9taient, ce qu&#8217;ils faisaient, et je pense que cela a \u00e9t\u00e9 tr\u00e8s agr\u00e9able, surtout pour les nouveaux propri\u00e9taires d&#8217;entreprises, de sentir que nous appartenons \u00e0 cette communaut\u00e9. Les gens nous soutiennent et veulent que nous soyons l\u00e0.<\/p><p>\u00a0<\/p><p>Je recommanderais absolument \u00e0 toute autre entreprise d&#8217;adh\u00e9rer \u00e0 la BIA. C&#8217;est un espace id\u00e9al pour \u00e9changer des id\u00e9es et faire du brainstorming, vous vous sentirez beaucoup plus au courant de ce qui se passe ici, qu&#8217;il s&#8217;agisse de nouveaux d\u00e9veloppements ou de nouveaux lieux qui s&#8217;ouvrent, c&#8217;est tout simplement une excellente source d&#8217;information. Il y a \u00e9galement beaucoup de ressources en termes de choses que vous pouvez utiliser pour votre entreprise, qu&#8217;il s&#8217;agisse d&#8217;aide \u00e0 la promotion ou de services aux entreprises, des choses que vous auriez du mal \u00e0 trouver ou \u00e0 contacter par vous-m\u00eame. Je lui donnerais sans h\u00e9siter une note de 10\/10. Ils ont \u00e9t\u00e9 incroyablement accueillants et nous ont beaucoup aid\u00e9s lors de l&#8217;ouverture de notre nouvelle entreprise et, encore une fois, je recommande vivement \u00e0 tous ceux qui le souhaitent de s&#8217;inscrire, car il n&#8217;en r\u00e9sulte que de la positivit\u00e9.<\/p><div dir=\"ltr\">\u00a0<\/div><div dir=\"ltr\">Elizabeth Iverson, Co-Owner Art of Bean Coffee Co.<\/div><div dir=\"ltr\">1439 Youville Dr Ottawa, ON K1C 4M8<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-00d8ae8 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"00d8ae8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ca7dd9 team_user_details\" data-id=\"5ca7dd9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2351c6f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2351c6f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f9e8330\" data-id=\"f9e8330\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9775f69 elementor-widget elementor-widget-video\" data-id=\"9775f69\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=6LS5FB2YM1E&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-268a8a9\" data-id=\"268a8a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5105ca elementor-widget elementor-widget-heading\" data-id=\"e5105ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">The Bad Alibi<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e758f1 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4e758f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jason Morrison , co-owner<\/p><p><span style=\"font-weight: 400;\">Je suis Jason Morris, nous avons ouvert il y a deux ans, je suis le propri\u00e9taire exploitant du Bad Alibi. Je suis tr\u00e8s heureux d&#8217;\u00eatre ici. J&#8217;ai aussi un partenaire, Matt Lewis. Nous sommes tous les deux des gars du coin, nous sommes ici depuis 1971, donc nous sommes dans la ville depuis le d\u00e9but d&#8217;Orl\u00e9ans !<\/span><\/p><p>\u00a0<\/p><p><span style=\"font-weight: 400;\">Nous avons ouvert le 16 juin il y a deux ans, \u00e0 la fin de la pand\u00e9mie, alors que COVID se terminait. Nous avons construit pendant le COVID, nous avons pris ce risque et nous avons dit &#8220;h\u00e9, essayons&#8221;.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-799eb3a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"799eb3a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ac95693\" data-id=\"ac95693\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0cade9b elementor-widget elementor-widget-text-editor\" data-id=\"0cade9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Nous avons ouvert le premier jour o\u00f9 nous avons \u00e9t\u00e9 l\u00e9galement autoris\u00e9s \u00e0 ouvrir le patio. Beaucoup d&#8217;\u00e9quipes viennent ici le soir. Pendant la journ\u00e9e, nous proposons des plats sp\u00e9ciaux pour le d\u00e9jeuner et le d\u00eener tout au long du week-end. Tous les deux mois, nous actualisons notre menu et y ajoutons trois ou quatre nouveaut\u00e9s. Nous ajoutons parfois de nouvelles entr\u00e9es, parfois des hamburgers, des sandwichs et des p\u00e2tes. Nous essayons de faire en sorte que tous les membres de la communaut\u00e9 puissent venir ici sans avoir l&#8217;impression de ne pas pouvoir manger ce qu&#8217;il y a sur le menu.\u00a0<\/span><\/p><p>\u00a0<\/p><p><span style=\"font-weight: 400;\">Au fil des ans, Matt et moi avons tous deux travaill\u00e9 dans le secteur. J&#8217;ai \u00e9t\u00e9 serveur\/barman et Matt a \u00e9t\u00e9 serveur\/barman, g\u00e9rant et propri\u00e9taire-exploitant de plusieurs \u00e9tablissements, mais c&#8217;est la premi\u00e8re fois que nous poss\u00e9dons quelque chose nous-m\u00eames. Nous nous sommes dit que nous allions essayer quelque chose de nouveau et que nous allions tout faire \u00e0 partir de z\u00e9ro. Rien de ce que vous voyez sur notre menu n&#8217;est congel\u00e9, nous l&#8217;apportons frais, pr\u00eat \u00e0 l&#8217;emploi et d&#8217;origine locale. Toute notre viande vient de Lavergnes, tous nos l\u00e9gumes viennent de Macartneys (Farm), nous nous approvisionnons \u00e9galement localement pour une grande partie de notre m\u00e9lange de printemps. Nous faisons cela sp\u00e9cifiquement pour que, lorsque vous franchissez la porte, le plat soit pr\u00e9par\u00e9 comme vous le feriez chez vous, sauf que nous le faisons pour vous et que nous nous occupons de tout.<\/span><\/p><p>\u00a0<\/p><p><span style=\"font-weight: 400;\">Les gens ne connaissent pas tous les restaurants d&#8217;Orl\u00e9ans, m\u00eame ceux qui vivent ici depuis toujours. Vous pouvez aller sur leur site pour voir ce qu&#8217;il y a pour vous, ce qui est disponible dans la r\u00e9gion, ce qui est disponible \u00e0 Orl\u00e9ans. C&#8217;est bien d&#8217;avoir un site qui fait cela pour vous, qui vous guide vers diff\u00e9rents endroits et vous donne la chance d&#8217;essayer des endroits locaux dans la r\u00e9gion.<\/span><\/p><p>\u00a0<\/p><p><span style=\"font-weight: 400;\">La ZAC est venue nous voir d\u00e8s le d\u00e9but, alors que nous \u00e9tions encore en train de construire, et elle nous a suivis un mois ou deux apr\u00e8s l&#8217;ouverture. Lorsque nous construisions, nous ne savions pas exactement ce qui se passait avec la pand\u00e9mie, quand elle allait se terminer, ce qui allait se passer, et il \u00e9tait donc difficile de se faire conna\u00eetre \u00e0 ce moment-l\u00e0. Mais une fois que nous avons adh\u00e9r\u00e9 et que nous nous sommes lanc\u00e9s, ils sont avec nous depuis le d\u00e9but.<\/span><\/p><p>\u00a0<\/p><p><span style=\"font-weight: 400;\">Il est toujours bon d&#8217;avoir une source locale pour trouver des choses ou parler aux gens. Il est bon d&#8217;avoir un groupe de personnes qui peuvent aider \u00e0 influencer une zone locale, ils donnent aux gens d&#8217;Orl\u00e9ans une chance de savoir ce qui se passe \u00e0 Orl\u00e9ans.\u00a0<\/span><\/p><p>\u00a0<\/p><p><span style=\"font-weight: 400;\">Tous les contacts que j&#8217;ai eus ont \u00e9t\u00e9 formidables, ils nous ont beaucoup soutenus, ils nous ont pos\u00e9 des questions, il n&#8217;y a pas eu de pression forc\u00e9e. C&#8217;est toujours un choix, nous sommes heureux de les soutenir et ils sont heureux de nous soutenir. En fait, en tant que restaurant local d&#8217;Orl\u00e9ans et en tant que gar\u00e7ons et employeurs locaux, nous voulons soutenir la communaut\u00e9 et les \u00e9v\u00e9nements locaux, nous voulons faire partie de la communaut\u00e9. Nous voulons que les membres de la communaut\u00e9 aient le sentiment que lorsqu&#8217;ils franchissent la porte, quel que soit leur milieu d&#8217;origine, ils sont toujours les bienvenus et nous sommes heureux de nous occuper d&#8217;eux pour que leur exp\u00e9rience soit la meilleure possible.<\/span><\/p><p>\u00a0<\/p><section class=\"elementor-section elementor-top-section elementor-element elementor-element-56c7326 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56c7326\" data-element_type=\"section\"><div class=\"elementor-container elementor-column-gap-default\"><div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f74668\" data-id=\"8f74668\" data-element_type=\"column\"><div class=\"elementor-widget-wrap elementor-element-populated\"><div class=\"elementor-element elementor-element-6a57bfc elementor-widget elementor-widget-text-editor\" data-id=\"6a57bfc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p>Jason Morris, Owner \u2013 The Bad Alibi<\/p><p>5935 Jeanne D\u2019Arc Blvd S, Orl\u00e9ans, ON K1C 2N1<\/p><p>(613) 424-7000<\/p><\/div><\/div><\/div><\/div><\/div><\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-822f32a quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"822f32a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cc1bc52 team_user_details\" data-id=\"cc1bc52\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-aa1629c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa1629c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-854017c\" data-id=\"854017c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3b03b3 elementor-widget elementor-widget-video\" data-id=\"b3b03b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=GNpaekV2NFc&amp;t=1s&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7bafc09\" data-id=\"7bafc09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94476eb elementor-widget elementor-widget-heading\" data-id=\"94476eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Gifty's<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9389adf elementor-widget elementor-widget-text-editor\" data-id=\"9389adf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Propri\u00e9taire, Gifty Abiad<\/span><\/p><p>\u00a0<\/p><p><span style=\"font-weight: 400;\">Je m&#8217;appelle Gifty Abiad et je suis la propri\u00e9taire de Gifty&#8217;s. Gifty&#8217;s est une entreprise de conception sur mesure, de retouches et de nettoyage \u00e0 sec. En fait, il s&#8217;agit d&#8217;un guichet unique. Nous nous occupons de vos v\u00eatements et du nettoyage \u00e0 sec. Nous nous occupons \u00e9galement de la pr\u00e9servation et de la restauration des v\u00eatements. Nous vendons \u00e9galement des accessoires pour am\u00e9liorer vos v\u00eatements, des \u00e9charpes, des bijoux, des enveloppes et des ponchos. Nous sommes situ\u00e9s au 2003 St Joseph Blvd, point de rep\u00e8re juste en face du Dairy Queen. Nous sommes en affaires depuis 10 ans, nous avons d\u00e9m\u00e9nag\u00e9 ici l&#8217;ann\u00e9e derni\u00e8re.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-df89630 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"df89630\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c5b3291\" data-id=\"c5b3291\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30a5a65 elementor-widget elementor-widget-text-editor\" data-id=\"30a5a65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La ZAC a \u00e9t\u00e9 formidable, en particulier pour notre d\u00e9m\u00e9nagement. Nous avons \u00e9t\u00e9 bloqu\u00e9s par le d\u00e9m\u00e9nagement, nous cherchions un autre emplacement et ils ont jou\u00e9 avec nous pendant environ huit mois, pendant que notre ancien emplacement \u00e9tait lou\u00e9 et que nous n&#8217;avions que deux mois pour chercher un endroit. Nous avons trouv\u00e9 cet endroit et, avec l&#8217;aide de la BIA, tout s&#8217;est d\u00e9roul\u00e9 en moins d&#8217;un mois. Tannis a \u00e9t\u00e9 formidable. Je l&#8217;ai appel\u00e9e et lui ai dit : &#8220;J&#8217;ai des probl\u00e8mes, j&#8217;ai des rendez-vous et je n&#8217;ai nulle part o\u00f9 travailler&#8221;. Toutes nos affaires \u00e9taient entrepos\u00e9es et ils sont intervenus pour nous aider et, en trois semaines, tout \u00e9tait construit. Chaque fois que j&#8217;ai eu besoin de quelque chose et que j&#8217;ai fait appel \u00e0 eux, ils ont \u00e9t\u00e9 pr\u00eats \u00e0 m&#8217;aider.<\/span><\/p><p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Il est bon de savoir qu&#8217;il y a quelqu&#8217;un qui se soucie de nous, que nous pouvons contacter parce que nous ne sommes qu&#8217;une goutte d&#8217;eau dans l&#8217;oc\u00e9an, alors savoir qu&#8217;il n&#8217;y a qu&#8217;un coup de fil \u00e0 passer ou que nous pouvons nous rendre \u00e0 leur bureau est tout simplement r\u00e9confortant. Nous avons beaucoup souffert, surtout avec le covid, et chaque fois qu&#8217;ils pensent que quelque chose peut nous \u00eatre utile, ils nous envoient un courriel et nous t\u00e9l\u00e9phonent m\u00eame.<\/span><\/p><p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Si je n&#8217;avais qu&#8217;un mot \u00e0 dire pour d\u00e9crire la ZAC, ce serait &#8220;incroyable&#8221;. C&#8217;est quelque chose qui est l\u00e0 pour aider les entreprises, donc les propri\u00e9taires d&#8217;entreprises devraient en profiter parce qu&#8217;ils peuvent faire beaucoup plus pour nous que ce que nous pouvons faire par nous-m\u00eames.<\/span><\/p><p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Lorsque j&#8217;ai assist\u00e9 \u00e0 ma premi\u00e8re r\u00e9union, qui \u00e9tait bien s\u00fbr en ligne, j&#8217;\u00e9tais un peu perdue et d\u00e9pass\u00e9e parce que, bien que j&#8217;aie dirig\u00e9 une entreprise, je n&#8217;avais jamais fait partie de la ZAC. En entendant les probl\u00e8mes des autres et les questions qu&#8217;ils posent, j&#8217;ai eu l&#8217;impression d&#8217;\u00eatre accompagn\u00e9e, de ne pas me sentir seule. Je ne savais pas qu&#8217;il existait quelque chose comme (la BIA) jusqu&#8217;\u00e0 ce que quelqu&#8217;un m&#8217;en parle un jour, alors que je d\u00e9m\u00e9nageais \u00e0 St Joseph.<\/span><\/p><div dir=\"ltr\">\u00a0<\/div><div dir=\"ltr\">Gifty Abiad, Owner &#8211; Gifty<\/div><div dir=\"ltr\">2003 St Joseph Blvd, Orl\u00e9ans, ON K1C 1E5<\/div><div dir=\"ltr\">(613) 424-6575<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-117e305 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"117e305\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a0c2bb7 team_user_details\" data-id=\"a0c2bb7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-de9c7cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de9c7cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e193233\" data-id=\"e193233\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a635073 elementor-widget elementor-widget-video\" data-id=\"a635073\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/BTlawioDyWk?si=JKgtNCgdwLsr0N02&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5752862\" data-id=\"5752862\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a26c42a elementor-widget elementor-widget-heading\" data-id=\"a26c42a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">The Tortillia Maker of Canada<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a29840a elementor-widget elementor-widget-text-editor\" data-id=\"a29840a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Miquel Jimenez, propri\u00e9taire<\/strong><\/p><p>\u00a0<\/p><p>&#8220;Bonjour, je m&#8217;appelle Miguel Jimenez et je suis le propri\u00e9taire de Tortilla Maker. Nous sommes situ\u00e9s au 2003 boul. St-Joseph \u00e0 Orl\u00e9ans, Ottawa. Nous venons d&#8217;ouvrir le 16 ao\u00fbt 2023. Nous sommes une tortilleria mexicaine traditionnelle et nous fabriquons d&#8217;authentiques tortillas de ma\u00efs. Nous utilisons un processus traditionnel de nixtamalisation qui a \u00e9t\u00e9 utilis\u00e9 pendant les 7000 derni\u00e8res ann\u00e9es au Mexique par les peuples indig\u00e8nes. Les tortillas sont d\u00e9licieuses car nous utilisons du ma\u00efs blanc biologique, de la chaux et de l&#8217;eau. Nous n&#8217;ajoutons pas de conservateurs, d&#8217;ar\u00f4mes artificiels, de sel ou quoi que ce soit d&#8217;autre. Le go\u00fbt, la texture et l&#8217;odeur sont authentiques, c&#8217;est tr\u00e8s bon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9e22593 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9e22593\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-aa83932\" data-id=\"aa83932\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9060b74 elementor-widget elementor-widget-text-editor\" data-id=\"9060b74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La ZAC nous a beaucoup aid\u00e9s, c&#8217;est une \u00e9quipe formidable. Elle nous soutient depuis le d\u00e9but et nous appr\u00e9cions tout le soutien qu&#8217;elle nous a apport\u00e9. Nous sommes tr\u00e8s heureux de faire partie de cette communaut\u00e9. Ils sont tr\u00e8s attach\u00e9s \u00e0 vous. Ils vous re\u00e7oivent, ils vous font sentir que vous \u00eates les bienvenus d\u00e8s la premi\u00e8re fois. Ils vous abordent de mani\u00e8re tr\u00e8s constructive, pour vous aider, pour r\u00e9soudre des probl\u00e8mes, pour vous guider, et parfois simplement pour vous parler et vous soutenir. Ils sont donc formidables. Il y a des r\u00e9unions pour les membres du BIA, qui sont tr\u00e8s constructives parce que vous pouvez les rencontrer et cr\u00e9er un sentiment de communaut\u00e9.<\/p><p>\u00a0<\/p><p>Pour moi, ils ont \u00e9t\u00e9 tr\u00e8s importants et ils m&#8217;ont apport\u00e9 tout leur soutien. D&#8217;apr\u00e8s ce que je vois et ce que j&#8217;entends des autres membres, ils ressentent la m\u00eame chose, ils ressentent le soutien et ils sont tr\u00e8s heureux. Si quelqu&#8217;un voulait d\u00e9marrer son entreprise ici, sur le boulevard Saint-Joseph \u00e0 Orl\u00e9ans, je pense que c&#8217;est le meilleur endroit pour le faire.<\/p><p>\u00a0<\/p><p>J&#8217;invite tous nos clients et voisins d&#8217;Orl\u00e9ans et d&#8217;Ottawa \u00e0 venir nous rendre visite au Tortilla Maker.<\/p><p>\u00a0<\/p><div dir=\"ltr\">Miguel Jimenez, propri\u00e9taire\u2013 The Tortilla Maker of Canada<\/div><div dir=\"ltr\">2003 St Joseph Blvd, Orl\u00e9ans, ON K1C 1E5<\/div><div dir=\"ltr\">(613) 698-3776<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-094bef6 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"094bef6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-692b2a9 team_user_details\" data-id=\"692b2a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-906ff7e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"906ff7e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0ab8e5e\" data-id=\"0ab8e5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b83c5e4 elementor-widget elementor-widget-video\" data-id=\"b83c5e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/7SxYbZaTvbc&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-652d9fa\" data-id=\"652d9fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc757e0 elementor-widget elementor-widget-heading\" data-id=\"dc757e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">School of Rock Orl\u00e9ans Rick Vantour<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1562335 elementor-widget elementor-widget-text-editor\" data-id=\"1562335\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Rick Vantour, propri\u00e9taire de School Of Rock Orl\u00e9ans, nouvellement r\u00e9nov\u00e9.\u00a0 L&#8217;\u00e9cole a ouvert ses portes en mars 2014. Ils enseignent la guitare, la base, le chant et la batterie. L&#8217;\u00e2ge des \u00e9tudiants va de 3 \u00e0 75 ans. Ils offrent des camps d&#8217;entra\u00eenement pour les groupes. Rick ajoute que la musique est un sport d&#8217;\u00e9quipe, pour les enfants qui ne se voient pas dans une \u00e9quipe sportive normale. Cela favorise le d\u00e9veloppement de la cr\u00e9ativit\u00e9 chez l&#8217;enfant. School of Rock, c&#8217;est la rencontre de la musique et de l&#8217;apprentissage<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-130d05b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"130d05b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-56c9c0a\" data-id=\"56c9c0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6682be4 elementor-widget elementor-widget-text-editor\" data-id=\"6682be4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Rick explique que la programmation de School of Rock varie en fonction de la demande de la personne. Rock 101 est l&#8217;un des meilleurs programmes de School of Rock Orl\u00e9ans pour les enfants et les d\u00e9butants. Les \u00e9l\u00e8ves ont une r\u00e9p\u00e9tition de groupe hebdomadaire au cours de laquelle ils apprennent \u00e0 jouer des morceaux de rock classiques qui ont \u00e9t\u00e9 simplifi\u00e9s pour les musiciens d\u00e9butants.\u00a0<\/p><p>\u00a0<\/p><p>\u00c0 la School of Rock Orl\u00e9ans, le programme musical Little Wing, destin\u00e9 aux enfants d&#8217;\u00e2ge pr\u00e9scolaire et aux tout-petits, enseigne les bases de la musique en jouant \u00e0 des jeux et en participant \u00e0 d&#8217;autres activit\u00e9s musicales interactives.<\/p><p>\u00a0<\/p><p>Notre programme Songwriting pour les enfants et les adolescents de 12 ans et plus enseigne les principes fondamentaux de l&#8217;\u00e9criture de chansons, de l&#8217;arrangement et de la th\u00e9orie musicale, et aide les \u00e9l\u00e8ves \u00e0 composer des \u0153uvres originales. Tous les deux mois, les \u00e9l\u00e8ves du programme Songwriting montent sur sc\u00e8ne pour se produire ou se regroupent pour enregistrer leurs chansons originales.<\/p><p>\u00a0<\/p><p>Rick ajoute que la ZAC apporte son soutien at toutes les entreprises\u00a0 locales,\u00a0 le co\u00fbt est minime et les r\u00e9sultats sont importants. Lorsque l&#8217;\u00e9cole de rock a commenc\u00e9, la ZAC \u00e9tait un moyen de communiquer avec les habitants d&#8217;Orl\u00e9ans. Il s&#8217;agit d&#8217;une entreprise unique et la ZAC a contribu\u00e9 \u00e0 la faire conna\u00eetre. La ZAC partage tous les \u00e9v\u00e9nements de School of Rock Orl\u00e9ans sur ses plateformes de m\u00e9dias sociaux. La School of Rock a particip\u00e9 \u00e0 l&#8217;\u00e9v\u00e9nement Lighting the Tree, ce qui a \u00e9t\u00e9 un excellent \u00e9v\u00e9nement de r\u00e9seautage pour montrer les \u00e9tudiants et la musique.<\/p><p>\u00a0<\/p><p>2003 St Joseph Blvd<\/p><p>Tel 613.841.8118<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f31d92 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f31d92\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cae0667 team_user_details\" data-id=\"cae0667\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-09c45d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"09c45d3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ad29a2d\" data-id=\"ad29a2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c60673 elementor-widget elementor-widget-text-editor\" data-id=\"3c60673\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-size: 24px; font-weight: 600; color: #000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-38211 alignright\" src=\"https:\/\/heartoforledev.wpenginepowered.com\/wp-content\/uploads\/2022\/02\/Screen-Shot-2021-02-09-at-2.36.35-PM-300x188.png\" alt=\"\" width=\"300\" height=\"188\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/Screen-Shot-2021-02-09-at-2.36.35-PM-300x188.png 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/Screen-Shot-2021-02-09-at-2.36.35-PM.png 696w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>The Love of Chocolate Factory<\/p><p>\u00a0<\/p><p style=\"font-size: 20px; color: #000;\">Moiz Hassanali, Owner<\/p><p>\u201cNotre soci\u00e9t\u00e9, The Love Of Chocolate Factory, aimerait mettre en lumi\u00e8re la fa\u00e7on dont la BIA du C\u0153ur d\u2019Orl\u00e9ans a contribu\u00e9 \u00e0 la croissance de notre entreprise.<\/p><p>L\u2019\u00e8re COVID-19 a \u00e9t\u00e9 difficile pour toutes les entreprises, mais la BIA a \u00e9norm\u00e9ment aid\u00e9 notre soci\u00e9t\u00e9 en ces temps difficiles.<\/p><p>Tannis a \u00e9t\u00e9 remarquable et a toujours fait tout son possible pour que nous obtenions toute l\u2019aide n\u00e9cessaire. Tannis, pendant la premi\u00e8re \u00e9tape de toutes les fermetures d\u2019entreprises non essentielles, nous a contact\u00e9s et a inscrit notre entreprise sur le site web de la ZAC, informant le public que nous sommes ouverts pour les ramassages et les livraisons sur le trottoir. C\u2019\u00e9tait un outil essentiel pour que les clients sachent que nous sommes ouverts pour les servir et cela a contribu\u00e9 \u00e0 attirer les clients dans notre magasin.<\/p><p>Elle a \u00e9galement entrepris une mission importante en ces temps difficiles pour s\u2019assurer que les citoyens les moins fortun\u00e9s aient de la nourriture sur la table gr\u00e2ce \u00e0 sa collecte de denr\u00e9es alimentaires.<\/p><p>Nous avons fait plusieurs demandes \u00e0 Tannis \u00e0 diff\u00e9rents niveaux concernant notre entreprise et elle s\u2019est occup\u00e9e de toutes efficacement sans aucun d\u00e9lai. Elle a m\u00eame r\u00e9pondu \u00e0 nos e-mails en dehors des heures de travail, elle est totalement d\u00e9vou\u00e9e \u00e0 son travail.<\/p><p>le rythme, la connexion en ligne a toujours \u00e9t\u00e9 tr\u00e8s productive, donnant toutes les mises \u00e0 jour de ce qui se passe dans notre belle Orl\u00e9ans. Ce petit mot est pour remercier la ZAC et surtout Tannis. Continuez le merveilleux travail d\u2019embellissement des rues d\u2019Orl\u00e9ans avec des fleurs, des banni\u00e8res et des bancs\u201d.<\/p><p>Moiz Hassanali, propri\u00e9taire The Love Of Chocolate Factory<\/p><p>2866 St Joseph Boulevard, Orl\u00e9ans, ON K1C 1G7<\/p><p>(613) 424-5031<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a395f08 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a395f08\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-86b1b9f team_user_details\" data-id=\"86b1b9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0d90cc5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d90cc5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-80d8a61\" data-id=\"80d8a61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01e8491 elementor-widget elementor-widget-text-editor\" data-id=\"01e8491\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-size: 24px; font-weight: 600; color: #000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-38209 alignleft\" src=\"https:\/\/heartoforledev.wpenginepowered.com\/wp-content\/uploads\/2022\/02\/IMG_4960-1-1200x1200-1-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/IMG_4960-1-1200x1200-1-300x300.jpg 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/IMG_4960-1-1200x1200-1-1024x1024.jpg 1024w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/IMG_4960-1-1200x1200-1-150x150.jpg 150w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/IMG_4960-1-1200x1200-1-768x768.jpg 768w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/IMG_4960-1-1200x1200-1.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Quilty Pleasures<\/p><p>\u00a0<\/p><p style=\"font-size: 20px; color: #000;\">Val Jensen, Co-Owner<\/p><p>\u201cLe boulevard St-Joseph est le c\u0153ur d\u2019Orl\u00e9ans, et la ZAC du C\u0153ur d\u2019Orl\u00e9ans en est le plus grand promoteur. Avec pr\u00e8s de 400 entreprises dans le secteur, la rue offre une vaste gamme de produits, de services et de restaurants, et la ZAC fait un travail ph\u00e9nom\u00e9nal pour les promouvoir et les soutenir.<\/p><p>Les bulletins d\u2019information r\u00e9guliers et les messages sur les m\u00e9dias sociaux de la ZAC, ainsi que le rythme et son site web, sont informatifs et attrayants, accueillant les nouvelles entreprises, r\u00e9introduisant les entreprises existantes et encourageant activement le public \u00e0 faire ses achats localement. Leur r\u00e9cente initiative \u201cles vidages des entreprises\u201d a fait un travail remarquable en nous rappelant que nos entreprises sont compos\u00e9es de personnes qui se soucient profond\u00e9ment de cette communaut\u00e9.<\/p><p>En ce qui concerne le soutien, la ZAC a vraiment fait un pas en avant pour aider les entreprises locales pendant cette p\u00e9riode extraordinaire de COVID. En fournissant des mises \u00e0 jour r\u00e9guli\u00e8res sur les r\u00e9glementations gouvernementales et les programmes d\u2019assistance, en assurant une liaison et une d\u00e9fense permanentes avec les trois niveaux de gouvernement, et en fournissant des outils pr\u00e9cieux pour aider les entreprises \u00e0 naviguer sur des eaux souvent troubles, la ZAC a prouv\u00e9 qu\u2019elle \u00e9tait fermement du c\u00f4t\u00e9 des entreprises locales. Si vous dirigez une entreprise dans la r\u00e9gion de Saint-Joseph, vous \u00eates peut-\u00eatre membre de la ZAC du C\u0153ur d\u2019Orl\u00e9ans sans m\u00eame le savoir. Si c\u2019est le cas, vous et votre entreprise \u00eates perdus !\u201d<\/p><p>Val Jensen, Co-propri\u00e9taire Quilty Pleasures<\/p><p>2211 St Joseph Boulevard, Orl\u00e9ans, ON K1C 7C5<\/p><p>(613) 834-3044<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-819c7ee quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"819c7ee\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dcfb155 team_user_details\" data-id=\"dcfb155\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-778c745 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"778c745\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f81c02a\" data-id=\"f81c02a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3351377 elementor-widget elementor-widget-text-editor\" data-id=\"3351377\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-size: 24px; font-weight: 600; color: #000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-38214 alignleft\" src=\"https:\/\/heartoforledev.wpenginepowered.com\/wp-content\/uploads\/2022\/02\/IMG_5229-1086x1536-1-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/IMG_5229-1086x1536-1-212x300.jpg 212w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/IMG_5229-1086x1536-1-724x1024.jpg 724w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/IMG_5229-1086x1536-1-768x1086.jpg 768w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/IMG_5229-1086x1536-1-300x424.jpg 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/IMG_5229-1086x1536-1.jpg 1086w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/>The Massage &amp; Treatment Centre<\/p><p style=\"font-size: 20px; color: #000;\">Amanda Smith<\/p><p>\u201cLa ZAC du Coeur d\u2019Orl\u00e9ans est la voix qui fait entendre les principaux enjeux \u00e9conomiques des entreprises locales. Elle collabore avec la Chambre de commerce d\u2019Ottawa, la ville, la province et les \u00e9lus f\u00e9d\u00e9raux pour s\u2019assurer que les vertus et les pr\u00e9occupations de notre communaut\u00e9 d\u2019affaires sont largement connues et prises en compte, ainsi que pour promouvoir notre r\u00e9gion comme destination touristique locale. En tant que propri\u00e9taire d\u2019entreprise, j\u2019ai directement b\u00e9n\u00e9fici\u00e9 de leur action de promotion par le biais de marketing promotionnel, de festivals locaux, d\u2019\u00e9v\u00e9nements et d\u2019embellissement. Je suis fier d\u2019avoir mon entreprise \u00e0 Orl\u00e9ans avec le soutien de ma ZAC locale\u201d.<\/p><p>Amanda Smith, Co-propri\u00e9taire The Massage and Treatment Centre<\/p><p>1224 Place d\u2019Orl\u00e9ans Dr unit 110, Orl\u00e9ans, ON K1C 7K3<\/p><p>(613) 837-2740<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66f1ae9 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66f1ae9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a5cb19b team_user_details\" data-id=\"a5cb19b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-361b17e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"361b17e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4f1619b\" data-id=\"4f1619b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed769f2 elementor-widget elementor-widget-text-editor\" data-id=\"ed769f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-size: 24px; font-weight: 600; color: #000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-38216 alignleft\" src=\"https:\/\/heartoforledev.wpenginepowered.com\/wp-content\/uploads\/2022\/02\/IMG_5004-1200x1200-1-300x300.jpg\" alt=\"IMG_5004\" width=\"300\" height=\"300\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/IMG_5004-1200x1200-1-300x300.jpg 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/IMG_5004-1200x1200-1-1024x1024.jpg 1024w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/IMG_5004-1200x1200-1-150x150.jpg 150w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/IMG_5004-1200x1200-1-768x768.jpg 768w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/IMG_5004-1200x1200-1.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Stray Dog Brewing Company<\/p><p style=\"font-size: 20px; color: #000;\">Marc Plante<\/p><p>\u201cLa ZAC du C\u0153ur d\u2019Orl\u00e9ans joue un r\u00f4le essentiel dans la promotion et le soutien des entreprises locales.<\/p><p>Le personnel et les membres du conseil d\u2019administration de la ZAA sont tr\u00e8s passionn\u00e9s par la c\u00e9l\u00e9bration de la communaut\u00e9 riche et diversifi\u00e9e qu\u2019est Orl\u00e9ans. Ils sont tr\u00e8s actifs dans la communication avec leurs membres ainsi qu\u2019avec leurs \u00e9lecteurs, en leur fournissant des nouvelles opportunes et informatives par le biais de divers canaux.<\/p><p>Tout au long de la pand\u00e9mie, la BIA a redoubl\u00e9 d\u2019efforts pour inciter les membres de la communaut\u00e9 \u00e0 faire leurs achats et \u00e0 soutenir les habitants, ce qui signifie beaucoup pour beaucoup d\u2019entre nous\u201d.<\/p><p>Marc Plante, Co-propri\u00e9taire Stray Dog Brewing Company<\/p><p>501 Lacolle Way Unit 4, Orl\u00e9ans, ON K4A 5B6, (613) 830-7364<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23d36bd quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23d36bd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-107c982 team_user_details\" data-id=\"107c982\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b01d930 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b01d930\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-84e5bc4\" data-id=\"84e5bc4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39b9d81 elementor-widget elementor-widget-text-editor\" data-id=\"39b9d81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-size: 24px; font-weight: 600; color: #000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-38315 alignleft\" src=\"https:\/\/heartoforledev.wpenginepowered.com\/wp-content\/uploads\/2022\/02\/Janet-brown-top-Sept-2014-photo-cropd-scaled-1-282x300.jpg\" alt=\"Janet-brown-top-Sept-2014-photo-cropd-scaled\" width=\"282\" height=\"300\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/Janet-brown-top-Sept-2014-photo-cropd-scaled-1-282x300.jpg 282w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/Janet-brown-top-Sept-2014-photo-cropd-scaled-1-962x1024.jpg 962w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/Janet-brown-top-Sept-2014-photo-cropd-scaled-1-768x818.jpg 768w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/Janet-brown-top-Sept-2014-photo-cropd-scaled-1-1442x1536.jpg 1442w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/Janet-brown-top-Sept-2014-photo-cropd-scaled-1-1200x1278.jpg 1200w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/Janet-brown-top-Sept-2014-photo-cropd-scaled-1-1400x1491.jpg 1400w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/Janet-brown-top-Sept-2014-photo-cropd-scaled-1-300x320.jpg 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/Janet-brown-top-Sept-2014-photo-cropd-scaled-1.jpg 1923w\" sizes=\"(max-width: 282px) 100vw, 282px\" \/>Money Coaches Canada<\/p><p>\u00a0<\/p><p style=\"font-size: 20px; color: #000;\">Janet Gray<\/p><p>\u201cJe suis heureux de soutenir mon milieu d\u2019affaires local en faisant de la publicit\u00e9 dans le rythme. J\u2019adore le fait que le rythme pr\u00e9sente divers magasins, bureaux et autres entreprises dans la rue principale de ma communaut\u00e9 de longue date et qu\u2019il me donne \u00e9galement des informations pratiques comme les mises \u00e0 jour municipales, les informations sur le m\u00e9tro l\u00e9ger \u00e0 venir et des conseils utiles pour les entreprises. C\u2019est un excellent moyen de se tenir au courant de l\u2019actualit\u00e9 de vos amis, voisins et entreprises dans votre communaut\u00e9 d\u2019Orl\u00e9ans\u201d.<\/p><p>Janet Gray, B.A., B. Admin., CFP\u00ae, EPC, CPCA<\/p><p>Money Coaches Canada<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-99335f4 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"99335f4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cb2b0aa team_user_details\" data-id=\"cb2b0aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8161a9a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8161a9a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-866ac99\" data-id=\"866ac99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71ba06e elementor-widget elementor-widget-text-editor\" data-id=\"71ba06e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-size: 24px; font-weight: 600; color: #000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-38219 alignleft\" src=\"https:\/\/heartoforledev.wpenginepowered.com\/wp-content\/uploads\/2022\/02\/Copy-of-andre-pic-240x300.jpg\" alt=\"andre\" width=\"240\" height=\"300\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/Copy-of-andre-pic-240x300.jpg 240w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/Copy-of-andre-pic-819x1024.jpg 819w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/Copy-of-andre-pic-768x960.jpg 768w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/Copy-of-andre-pic-300x375.jpg 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/02\/Copy-of-andre-pic.jpg 1024w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/>Beachcomber Hot Tubs<\/p><p>\u00a0<\/p><p style=\"font-size: 20px; color: #000;\">Andr\u00e9 Grzela<\/p><p>\u201cThe Beat est un endroit formidable pour faire de la publicit\u00e9 \u2013 l\u2019exposition locale est ce dont il s\u2019agit et il a attir\u00e9 de nouveaux clients quelques jours apr\u00e8s sa sortie num\u00e9rique. Il offre un excellent rapport qualit\u00e9-prix et je recommande vivement \u00e0 toute entreprise locale d\u2019Orl\u00e9ans de faire de la publicit\u00e9 dans le rythme\u201d.<\/p><p>Andr\u00e9 Grzela, propri\u00e9taire Beachcomber Hot Tubs<\/p><p>1993 St \u2013 Joseph, Orl\u00e9ans, ON, Canada K1C 1E5<\/p><p>(613) 837-2929<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9796a59 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9796a59\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20d2c58 team_user_details\" data-id=\"20d2c58\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-06e86f6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06e86f6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-db4363f\" data-id=\"db4363f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebd75e6 elementor-widget elementor-widget-text-editor\" data-id=\"ebd75e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-43683 size-medium alignleft\" src=\"https:\/\/heartoforledev.wpenginepowered.com\/wp-content\/uploads\/2022\/05\/Catherine-300x300.jpeg\" alt=\"Catherine\" width=\"300\" height=\"300\" \/><\/p><div><p style=\"font-size: 24px; font-weight: 600; color: #000;\">CP Business Solutions<\/p><p style=\"font-size: 20px; color: #000;\">Catherine Priestman<\/p><p>\u201cEn tant que membre associ\u00e9 de la ZAC du C\u0153ur d&#8217;Orl\u00e9ans, je suis toujours reconnaissant d&#8217;avoir la possibilit\u00e9 de faire partie de l&#8217;organisation. La ZAC est une source centrale d&#8217;information sur les entreprises locales et un centre de liaison indispensable. Mon adh\u00e9sion a un impact certain sur l&#8217;endroit o\u00f9 je fais mes achats et o\u00f9 je fais des affaires, et elle s&#8217;est rembours\u00e9e dix fois. Connexions. Des recommandations. Des pistes. Informations. Communaut\u00e9. La ZAC joue un r\u00f4le essentiel dans notre communaut\u00e9 d&#8217;affaires.&#8221;<\/p><p>Catherine Priestman, Owner CP Business Solutions<\/p><p>Orl\u00e9ans, Ontario<\/p><p>(613) 791-5670<\/p><p dir=\"ltr\">\u00a0<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-27bbe27 quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"27bbe27\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-16042f8 team_user_details\" data-id=\"16042f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-947f8f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"947f8f4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7ea109f\" data-id=\"7ea109f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebfe900 elementor-widget elementor-widget-text-editor\" data-id=\"ebfe900\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-43771 size-medium alignleft\" src=\"https:\/\/heartoforledev.wpenginepowered.com\/wp-content\/uploads\/2022\/05\/Patricia-300x300.jpeg\" alt=\"Patricia\" width=\"300\" height=\"300\" \/>\u00a0<\/p><p style=\"font-size: 24px; font-weight: 600; color: #000;\">La banque royal du Canada<\/p><p>\u00a0<\/p><p style=\"font-size: 20px; color: #000;\">Patricia Bonacci<\/p><p>\u201cRBC \u00e9tait membre de la ZAC du C\u0153ur d&#8217;Orl\u00e9ans lorsque nous \u00e9tions situ\u00e9s sur le boulevard Centrum. \u00c0 cette \u00e9poque, nous \u00e9tions \u00e9galement membres de la Chambre d&#8217;Orl\u00e9ans qui a depuis \u00e9t\u00e9 fusionn\u00e9e avec 2 autres chambres de la ville pour former la Chambre de commerce d&#8217;Orl\u00e9ans (OBOT). Lorsque l&#8217;OBOT a \u00e9t\u00e9 fusionn\u00e9e, nous n&#8217;avons pas vraiment r\u00e9fl\u00e9chi \u00e0 la fa\u00e7on dont la ZAC d&#8217;Orl\u00e9ans englobe notre communaut\u00e9 locale. Nous avons toutefois particip\u00e9 \u00e0 des journ\u00e9es de nettoyage et assist\u00e9 \u00e0 quelques \u00e9v\u00e9nements. Nous n&#8217;avions tout simplement pas r\u00e9alis\u00e9 tout ce que la ZAC fait pour Orl\u00e9ans. Quelques ann\u00e9es plus tard, avec le d\u00e9m\u00e9nagement de la succursale RBC juste en bas de la rue, nous avons contact\u00e9 la ZAC pour voir comment nous pourrions collaborer ensemble pour \u00eatre dans la communaut\u00e9. C&#8217;est alors que nous avons d\u00e9couvert qu&#8217;en raison du d\u00e9m\u00e9nagement, nous \u00e9tions situ\u00e9s juste en dehors du district de la ZAC et n&#8217;\u00e9tions plus membres. La ZAC nous a propos\u00e9 un statut de membre associ\u00e9 qui offrait les m\u00eames avantages qu&#8217;un membre, \u00e0 l&#8217;exception du droit de vote. Apr\u00e8s avoir discut\u00e9 avec les deux merveilleuses dames de la ZAC (Tannis et Rita), il n&#8217;y avait pas \u00e0 h\u00e9siter&#8230; Nous devions devenir membres associ\u00e9s !<\/p><p>\u00a0<\/p><p>Depuis que nous sommes devenus membres associ\u00e9s il y a un peu plus de deux ans, nous nous sommes engag\u00e9s dans la communaut\u00e9 d&#8217;Orl\u00e9ans, nous avons fait du r\u00e9seautage lors d&#8217;\u00e9v\u00e9nements virtuels, nous avons distribu\u00e9 des porte-cl\u00e9s de la ZAC et nous sommes m\u00eame all\u00e9s dans les entreprises locales pour voir &#8220;qui est qui&#8221; dans la communaut\u00e9 d&#8217;Orl\u00e9ans. Il a \u00e9t\u00e9 formidable de conna\u00eetre la plupart des entreprises d&#8217;Orl\u00e9ans que nous n&#8217;aurions pas connues si nous n&#8217;\u00e9tions pas devenus membres associ\u00e9s. En tant que membres associ\u00e9s, nous avons \u00e9t\u00e9 engag\u00e9s dans la campagne des visages d&#8217;entreprises de la ZAC, on nous a demand\u00e9 d&#8217;ajouter des conseils financiers perspicaces dans le bulletin d&#8217;information et nous sommes devenus membres du comit\u00e9 d&#8217;engagement des membres o\u00f9 nous avons \u00e9tabli des relations approfondies avec les autres membres de la ZAC !<\/p><p>\u00a0<\/p><p>Pour r\u00e9sumer, il est tr\u00e8s gratifiant d&#8217;\u00eatre un membre associ\u00e9 de la ZAC du C\u0153ur d&#8217;Orl\u00e9ans. Cela a rapproch\u00e9 la communaut\u00e9 d&#8217;Orl\u00e9ans et nous avons h\u00e2te de poursuivre notre relation avec la ZAC dans les ann\u00e9es \u00e0 venir !<\/p><p>\u00a0<\/p><p>Patricia Bonacci,\u00a0 Directrice communautaire &#8211; Rideau Lakes | Banque Royale du Canada<\/p><p>343-996-370<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-163dd3e quote_img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"163dd3e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce8b6da team_user_details\" data-id=\"ce8b6da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f578345 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f578345\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a99f0b2\" data-id=\"a99f0b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1944908 elementor-widget elementor-widget-text-editor\" data-id=\"1944908\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-45262 size-medium alignleft\" src=\"https:\/\/heartoforledev.wpenginepowered.com\/wp-content\/uploads\/2022\/06\/Steffi-Acevedo-Website-2-300x300.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/06\/Steffi-Acevedo-Website-2-300x300.png 300w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/06\/Steffi-Acevedo-Website-2-150x150.png 150w, https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/06\/Steffi-Acevedo-Website-2.png 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<\/p><div><p style=\"font-size: 24px; font-weight: 600; color: #000;\">ACE Arte Studio<\/p><p style=\"font-size: 20px; color: #000;\">Steffi Acevedo<\/p><p>\u00a0<\/p><p>\u201cEn La ZAC du c\u0153ur d&#8217;Orl\u00e9ans a jou\u00e9 un r\u00f4le d\u00e9terminant dans la promotion de ma nouvelle entreprise ACE Arte Studio aupr\u00e8s de la communaut\u00e9. C&#8217;est un plaisir de travailler avec Tannis, Rita et tous les membres de la ZAC ! Un grand merci !&#8221;<\/p><p>\u00a0<\/p><p>Steffi Acevedo, Owner Owner ACE Arte Studio<\/p><p>2095 St-Joseph Boulevard Orl\u00e9ans, Ontario<\/p><p>(613) 590-1010<\/p><p dir=\"ltr\">\u00a0<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Temoignages Il est toujours agr\u00e9able de recevoir des commentaires positifs de nos membres et membres associ\u00e9s. Cela nous aide \u00e0 comprendre ce que nous faisons bien et sur quoi nous &hellip;<\/p>\n","protected":false},"author":451,"featured_media":0,"parent":38146,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_genesis_block_theme_hide_title":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"class_list":["post-94964","page","type-page","status-publish","hentry","post","without-featured-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00e9moignages - Heart of Orl\u00e9ans BIA<\/title>\n<meta name=\"description\" content=\"Temoignages Il est toujours agr\u00e9able de recevoir des commentaires positifs de nos membres et membres associ\u00e9s. Cela nous aide \u00e0 comprendre ce que nous | Heart of Orl\u00e9ans BIA\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/heartoforleans.ca\/about-us\/testimonials\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9moignages - Heart of Orl\u00e9ans BIA\" \/>\n<meta property=\"og:description\" content=\"Temoignages Il est toujours agr\u00e9able de recevoir des commentaires positifs de nos membres et membres associ\u00e9s. Cela nous aide \u00e0 comprendre ce que nous | Heart of Orl\u00e9ans BIA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/heartoforleans.ca\/about-us\/testimonials\/\" \/>\n<meta property=\"og:site_name\" content=\"Heart of Orl\u00e9ans BIA\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:17:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/09\/fries.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"53 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/heartoforleans.ca\\\/about-us\\\/testimonials\\\/\",\"url\":\"https:\\\/\\\/heartoforleans.ca\\\/about-us\\\/testimonials\\\/\",\"name\":\"T\u00e9moignages - Heart of Orl\u00e9ans BIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/heartoforleans.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/heartoforleans.ca\\\/about-us\\\/testimonials\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/heartoforleans.ca\\\/about-us\\\/testimonials\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/heartoforleans.ca\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/fries.png\",\"datePublished\":\"2025-05-05T08:13:47+00:00\",\"dateModified\":\"2026-07-08T12:17:38+00:00\",\"description\":\"Temoignages Il est toujours agr\u00e9able de recevoir des commentaires positifs de nos membres et membres associ\u00e9s. Cela nous aide \u00e0 comprendre ce que nous | Heart of Orl\u00e9ans BIA\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/heartoforleans.ca\\\/about-us\\\/testimonials\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/heartoforleans.ca\\\/about-us\\\/testimonials\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/heartoforleans.ca\\\/about-us\\\/testimonials\\\/#primaryimage\",\"url\":\"https:\\\/\\\/heartoforleans.ca\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/fries.png\",\"contentUrl\":\"https:\\\/\\\/heartoforleans.ca\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/fries.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/heartoforleans.ca\\\/about-us\\\/testimonials\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/heartoforleans.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c0 notre sujet\",\"item\":\"https:\\\/\\\/heartoforleans.ca\\\/about-us\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"T\u00e9moignages\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/heartoforleans.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/heartoforleans.ca\\\/fr\\\/\",\"name\":\"Heart of Orl\u00e9ans BIA\",\"description\":\"Your SUPER-powered WP Engine Site\",\"publisher\":{\"@id\":\"https:\\\/\\\/heartoforleans.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/heartoforleans.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/heartoforleans.ca\\\/fr\\\/#organization\",\"name\":\"Heart of Orl\u00e9ans\",\"url\":\"https:\\\/\\\/heartoforleans.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/heartoforleans.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/heartoforleans.ca\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/pic-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/heartoforleans.ca\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/pic-logo.jpg\",\"width\":360,\"height\":220,\"caption\":\"Heart of Orl\u00e9ans\"},\"image\":{\"@id\":\"https:\\\/\\\/heartoforleans.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9moignages - Heart of Orl\u00e9ans BIA","description":"Temoignages Il est toujours agr\u00e9able de recevoir des commentaires positifs de nos membres et membres associ\u00e9s. Cela nous aide \u00e0 comprendre ce que nous | Heart of Orl\u00e9ans BIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/heartoforleans.ca\/about-us\/testimonials\/","og_locale":"fr_FR","og_type":"article","og_title":"T\u00e9moignages - Heart of Orl\u00e9ans BIA","og_description":"Temoignages Il est toujours agr\u00e9able de recevoir des commentaires positifs de nos membres et membres associ\u00e9s. Cela nous aide \u00e0 comprendre ce que nous | Heart of Orl\u00e9ans BIA","og_url":"https:\/\/heartoforleans.ca\/about-us\/testimonials\/","og_site_name":"Heart of Orl\u00e9ans BIA","article_modified_time":"2026-07-08T12:17:38+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/09\/fries.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"53 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/heartoforleans.ca\/about-us\/testimonials\/","url":"https:\/\/heartoforleans.ca\/about-us\/testimonials\/","name":"T\u00e9moignages - Heart of Orl\u00e9ans BIA","isPartOf":{"@id":"https:\/\/heartoforleans.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/heartoforleans.ca\/about-us\/testimonials\/#primaryimage"},"image":{"@id":"https:\/\/heartoforleans.ca\/about-us\/testimonials\/#primaryimage"},"thumbnailUrl":"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/09\/fries.png","datePublished":"2025-05-05T08:13:47+00:00","dateModified":"2026-07-08T12:17:38+00:00","description":"Temoignages Il est toujours agr\u00e9able de recevoir des commentaires positifs de nos membres et membres associ\u00e9s. Cela nous aide \u00e0 comprendre ce que nous | Heart of Orl\u00e9ans BIA","breadcrumb":{"@id":"https:\/\/heartoforleans.ca\/about-us\/testimonials\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/heartoforleans.ca\/about-us\/testimonials\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/heartoforleans.ca\/about-us\/testimonials\/#primaryimage","url":"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/09\/fries.png","contentUrl":"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2025\/09\/fries.png"},{"@type":"BreadcrumbList","@id":"https:\/\/heartoforleans.ca\/about-us\/testimonials\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/heartoforleans.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c0 notre sujet","item":"https:\/\/heartoforleans.ca\/about-us\/"},{"@type":"ListItem","position":3,"name":"T\u00e9moignages"}]},{"@type":"WebSite","@id":"https:\/\/heartoforleans.ca\/fr\/#website","url":"https:\/\/heartoforleans.ca\/fr\/","name":"Heart of Orl\u00e9ans BIA","description":"Your SUPER-powered WP Engine Site","publisher":{"@id":"https:\/\/heartoforleans.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/heartoforleans.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/heartoforleans.ca\/fr\/#organization","name":"Heart of Orl\u00e9ans","url":"https:\/\/heartoforleans.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/heartoforleans.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/03\/pic-logo.jpg","contentUrl":"https:\/\/heartoforleans.ca\/wp-content\/uploads\/2022\/03\/pic-logo.jpg","width":360,"height":220,"caption":"Heart of Orl\u00e9ans"},"image":{"@id":"https:\/\/heartoforleans.ca\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/heartoforleans.ca\/fr\/wp-json\/wp\/v2\/pages\/94964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heartoforleans.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/heartoforleans.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/heartoforleans.ca\/fr\/wp-json\/wp\/v2\/users\/451"}],"replies":[{"embeddable":true,"href":"https:\/\/heartoforleans.ca\/fr\/wp-json\/wp\/v2\/comments?post=94964"}],"version-history":[{"count":51,"href":"https:\/\/heartoforleans.ca\/fr\/wp-json\/wp\/v2\/pages\/94964\/revisions"}],"predecessor-version":[{"id":164911,"href":"https:\/\/heartoforleans.ca\/fr\/wp-json\/wp\/v2\/pages\/94964\/revisions\/164911"}],"up":[{"embeddable":true,"href":"https:\/\/heartoforleans.ca\/fr\/wp-json\/wp\/v2\/pages\/38146"}],"wp:attachment":[{"href":"https:\/\/heartoforleans.ca\/fr\/wp-json\/wp\/v2\/media?parent=94964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}